{"id":5225,"date":"2022-06-27T09:25:49","date_gmt":"2022-06-27T07:25:49","guid":{"rendered":"https:\/\/wp.unil.ch\/uniscope\/?p=5225"},"modified":"2024-04-15T15:20:23","modified_gmt":"2024-04-15T13:20:23","slug":"patient-et-systeme-de-sante-vers-un-changement-de-culture","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/uniscope\/patient-et-systeme-de-sante-vers-un-changement-de-culture\/","title":{"rendered":"Patient et syst\u00e8me de sant\u00e9\u00a0: vers un changement de culture"},"content":{"rendered":"\n<p><strong>Clap de fin pour les patients perdus dans la jungle des soins&nbsp;? Pas encore. Mais des \u00e9volutions vers le partenariat dans le domaine de la sant\u00e9 se font toujours plus fortes, comme le montrent deux \u00e9tudes men\u00e9es par le ColLaboratoire.<\/strong><\/p>\n\n\n\n<p>Le syst\u00e8me de sant\u00e9 tel que nous le connaissons aujourd\u2019hui aurait-il fait son temps&nbsp;? C\u2019est en partie ce que laissent penser les r\u00e9sultats de deux enqu\u00eates men\u00e9es par le ColLaboratoire de l\u2019UNIL. Mandat\u00e9 par la Direction g\u00e9n\u00e9rale de la sant\u00e9 du canton de Vaud d\u2019une part, ainsi que par la Fondation Leenaards d\u2019autre part, l\u2019unit\u00e9 de recherche-action collaborative et participative de l\u2019Universit\u00e9 de Lausanne r\u00e9v\u00e8le notamment une demande forte et toujours plus accrue d\u2019int\u00e9gration des patients et de leurs proches dans le domaine des soins.<\/p>\n\n\n\n<p>Si des changements en ce sens s\u2019op\u00e8rent dans certains champs de la m\u00e9decine depuis plusieurs d\u00e9cennies, comme en psychiatrie et dans les maladies rares, domaines pr\u00e9curseurs de l\u2019int\u00e9gration de patients-experts et patients-partenaires, une refonte globale du syst\u00e8me de sant\u00e9, malgr\u00e9 un consensus des diff\u00e9rents acteurs, se heurte encore \u00e0 de nombreux obstacles. Tour d\u2019horizon avec le ColLaboratoire.<\/p>\n\n\n\n<p><strong>Voix de la sant\u00e9<\/strong><\/p>\n\n\n\n<p>\u00ab&nbsp;Le renforcement du partenariat entre patients, proches et professionnels, ainsi que la n\u00e9cessit\u00e9 de d\u00e9velopper des possibilit\u00e9s de s\u2019\u00e9carter des processus habituellement d\u00e9ploy\u00e9s lorsqu\u2019ils sont inad\u00e9quats, au profit de v\u00e9ritables innovations, sont des demandes formul\u00e9es par l\u2019ensemble de acteurs&nbsp;\u00bb, souligne Alain Kaufmann, directeur du ColLaboratoire. Tel est l\u2019un des r\u00e9sultats de l\u2019enqu\u00eate \u00ab&nbsp;Voix de la sant\u00e9&nbsp;\u00bb, qui a recueilli les t\u00e9moignages d\u2019une quarantaine de patients, de proches et de professionnels de la sant\u00e9 autour de la question de la qualit\u00e9 et de la s\u00e9curit\u00e9 des soins. Il s\u2019agit d\u2019entretiens de recherche qualitatifs, dont une version est publi\u00e9e sous forme de podcasts et de vid\u00e9os, <a href=\"https:\/\/www.vd.ch\/themes\/sante-soins-et-handicap\/patients-et-residents-droits-et-qualite-de-soins\/la-qualite-des-soins\/qualite-des-soins-etude-scientifique-voix-de-la-sante\/\">\u00e0 d\u00e9couvrir en ligne<\/a>.<\/p>\n\n\n\n<p>La qualit\u00e9&nbsp;? <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;Des normes et des indicateurs qui en disent souvent assez peu sur la fa\u00e7on dont les soins se d\u00e9roulent concr\u00e8tement sur le terrain, sur le degr\u00e9 de satisfaction des usagers au regard des soins dispens\u00e9s ou les pistes d\u2019am\u00e9lioration imagin\u00e9es par les professionnels&nbsp;\u00bb.  <\/p><cite>Alain Kaufmann. <\/cite><\/blockquote>\n\n\n\n<p>Des crit\u00e8res qui visent toutefois \u00e0 produire les meilleurs soins possibles dans les organisations, pr\u00e9cise le chercheur. Reste qu\u2019aujourd\u2019hui les patients, leurs proches, les groupes et associations de malades revendiquent toujours plus de participer au d\u00e9veloppement de la \u00ab&nbsp;d\u00e9cision partag\u00e9e&nbsp;\u00bb, au partenariat en sant\u00e9, \u00e0 la coproduction de soins, ainsi qu\u2019\u00e0 l\u2019orientation de la recherche biom\u00e9dicale&nbsp;; afin d\u2019int\u00e9grer, enfin, la qualit\u00e9 r\u00e9elle per\u00e7ue par les usagers. \u00ab&nbsp;La Suisse a un retard consid\u00e9rable en mati\u00e8re d\u2019inclusion des usagers et de coproduction de la sant\u00e9, souligne encore Alain Kaufmann, qui prend pour exemple les maladies rares. Elles touchent environ 550&rsquo;000 personnes en Suisse. Cela fait moins de dix ans que la Conf\u00e9d\u00e9ration s\u2019est dot\u00e9e d\u2019un plan d\u2019action dans ce domaine, et il a \u00e9t\u00e9 mis en place suite \u00e0 une \u00e9mission de t\u00e9l\u00e9vision mettant l\u2019accent sur l\u2019inanit\u00e9 de la prise en charge de patients touch\u00e9s par ce type de pathologies. Ce qu\u2019on appelle l\u2019errance th\u00e9rapeutique.&nbsp;\u00bb Autre \u00e9l\u00e9ment majeur relev\u00e9 parmi les r\u00e9sultats de l\u2019enqu\u00eate \u00ab&nbsp;Voix de la sant\u00e9&nbsp;\u00bb&nbsp;: le manque de coordination des soins, \u00e9galement point\u00e9 dans la seconde enqu\u00eate men\u00e9e par le ColLaboratoire.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;Mais je veux surtout insister sur le fait que notre enqu\u00eate met en \u00e9vidence des dizaines de pistes d\u2019am\u00e9lioration \u00e0 disposition des autorit\u00e9s cantonales, imagin\u00e9es par les personnes que nous avons interrog\u00e9es&nbsp;!&nbsp;\u00bb d\u00e9clare Alain Kaufmann avec enthousiasme.<\/p><\/blockquote>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Sant\u00e9 int\u00e9grative<\/strong><\/h5>\n\n\n\n<p>Dans le cadre de <a href=\"https:\/\/www.santeintegrative.ch\/\">l\u2019initiative \u00ab&nbsp;Sant\u00e9 int\u00e9grative &amp; soci\u00e9t\u00e9&nbsp;\u00bb<\/a>, programme de cinq ans lanc\u00e9 par la Fondation Leenaards, le ColLaboratoire a r\u00e9alis\u00e9 la premi\u00e8re \u00e9tude majeure sur cette th\u00e9matique \u00e0 l\u2019\u00e9chelle romande, en collaboration avec FORS, le centre de comp\u00e9tence suisse en sciences sociales. La sant\u00e9 int\u00e9grative est un concept n\u00e9 principalement aux \u00c9tats-Unis, qui vise \u00e0 fournir aux patients des recours th\u00e9rapeutiques incluant l\u2019ensemble des pratiques de soins, ind\u00e9pendamment du degr\u00e9 de l\u00e9gitimit\u00e9 scientifique de ces derni\u00e8res. Un champ recouvrant tant la m\u00e9decine \u00ab&nbsp;conventionnelle&nbsp;\u00bb que les approches dites \u00ab&nbsp;compl\u00e9mentaires&nbsp;\u00bb. Par exemple l\u2019acupuncture, l\u2019hom\u00e9opathie, le reiki, l\u2019ayurveda, les faiseurs de secret, la r\u00e9flexologie, etc., aussi appel\u00e9es m\u00e9decines naturelles ou alternatives, peu int\u00e9gr\u00e9es dans la tradition acad\u00e9mique ou le syst\u00e8me de sant\u00e9.<\/p>\n\n\n\n<p>Dans les grandes lignes, <a href=\"https:\/\/www.santeintegrative.ch\/Actualites\/Enquete-menee-aupres-des-Romands-sur-la-sante-integrative-les-resultats-sont-la\">les r\u00e9sultats de l\u2019enqu\u00eate<\/a>, \u00e0 laquelle ont particip\u00e9 pr\u00e8s de 900 Romandes et Romands, montrent que 85% de la population souhaitent avoir un r\u00f4le important ou tr\u00e8s important dans le choix des professionnels \u00e0 consulter&nbsp;; 78% d\u00e9sirent tenir un r\u00f4le soutenu ou tr\u00e8s soutenu dans la coordination des soins et dans les choix des orientations th\u00e9rapeutiques et traitements. Un besoin l\u00e0 encore de se faire entendre, mais surtout d\u2019\u00eatre pleinement actrice et acteur dans une d\u00e9marche de soin, pour une population qui a toujours plus recours aux diff\u00e9rents types de m\u00e9decine (75% des r\u00e9pondantes et r\u00e9pondants disent avoir consult\u00e9 un ou une th\u00e9rapeute issus d\u2019une approche compl\u00e9mentaire).<\/p>\n\n\n\n<p>\u00ab&nbsp;Il est int\u00e9ressant de noter que le facteur d\u00e9terminant dans les processus de soins ressortant de notre enqu\u00eate est le degr\u00e9 de confiance envers le th\u00e9rapeute. Il est positionn\u00e9 par les r\u00e9pondants avant la preuve scientifique.&nbsp;\u00bb Ce qui indiquerait une baisse de confiance, un d\u00e9saveu de la science&nbsp;? \u00ab&nbsp;Non, r\u00e9pond cat\u00e9goriquement Alain Kaufmann. Le degr\u00e9 de confiance envers les chercheurs et chercheuses reste tr\u00e8s \u00e9lev\u00e9. Mais il y a une \u00e9volution globale vers une volont\u00e9 accrue de participation, de cr\u00e9er une v\u00e9ritable alliance th\u00e9rapeutique. Le paternalisme m\u00e9dical est critiqu\u00e9, y compris au sein des \u00e9tudes m\u00e9dicales. Aujourd\u2019hui, on forme les \u00e9tudiantes et \u00e9tudiants \u00e0 l\u2019empathie, \u00e0 l\u2019\u00e9coute, \u00e0 consid\u00e9rer que la d\u00e9cision partag\u00e9e est un facteur de r\u00e9ussite th\u00e9rapeutique.&nbsp;\u00bb<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Quel avenir&nbsp;?<\/strong><\/h5>\n\n\n\n<p>Impossible de pr\u00e9dire les d\u00e9marches entreprises par les autorit\u00e9s de sant\u00e9 et les changements concrets sur la base des r\u00e9sultats d\u2019enqu\u00eates de ce type. Une certitude en revanche&nbsp;: \u00ab&nbsp;Le syst\u00e8me de sant\u00e9 doit \u00eatre d\u00e9cloisonn\u00e9, assure Alain Kaufmann. Il faut r\u00e9ussir \u00e0 mieux coordonner les acteurs de la sant\u00e9. De la m\u00eame mani\u00e8re qu\u2019on a un probl\u00e8me avec la coordination des soins pour un patient particulier, on a un probl\u00e8me dans la coordination des acteurs de la sant\u00e9. Avec une d\u00e9perdition consid\u00e9rable d\u2019\u00e9nergie, de ressources et d\u2019expertise.&nbsp;\u00bb<\/p>\n\n\n\n<p>Reste que des partenariats concrets montrent clairement la n\u00e9cessit\u00e9 d\u2019int\u00e9grer toutes les parties concern\u00e9es dans le domaine de la sant\u00e9. \u00ab&nbsp;Dans le champ de la psychiatrie, le CHUV travaille par exemple sur les effets de la contrainte dans le cadre des hospitalisations forc\u00e9es. Sur ces questions, les recherches ont int\u00e9gr\u00e9 des patientes-expertes ou pairs-praticiennes dans les \u00e9quipes. Ces personnes travaillent aussi \u00e0 l\u2019\u00e9laboration de protocoles, comme des documents de consensus, par exemple le \u00ab&nbsp;plan de crise conjoint&nbsp;\u00bb, qui fixe \u00e0 l\u2019avance, en accord avec la patiente, comment une future crise devra \u00eatre g\u00e9r\u00e9e. Ces personnes interviennent aussi dans la formation des m\u00e9decins en psychopharmacologie. Quand on a \u00e9t\u00e9 affect\u00e9 par une maladie psychique, on a une expertise incontournable sur les effets des antid\u00e9presseurs, des neuroleptiques ou des anxiolytiques&nbsp;\u00bb, illustre le directeur du ColLaboratoire. Sans compter la mont\u00e9e en puissance d\u2019associations de patients de fa\u00e7on g\u00e9n\u00e9rale, \u00ab&nbsp;qui ont donn\u00e9 des impulsions bas\u00e9es sur des rapports de force politiques et des \u00e9v\u00e9nements comme l\u2019\u00e9pid\u00e9mie de sida ou la recherche sur les maladies rares.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0L\u2019industrie pharmaceutique aussi s\u2019est rendu compte il y a une vingtaine d\u2019ann\u00e9es que si elle souhaitait d\u00e9velopper des m\u00e9dicaments ou mener des essais cliniques, elle ne pouvait pas passer \u00e0 c\u00f4t\u00e9 des associations.&nbsp;\u00bb<\/p><cite>Alain Kaumann<\/cite><\/blockquote>\n\n\n\n<p>Le syst\u00e8me de sant\u00e9 devra-t-il donc faire face \u00e0 un d\u00e9fi titanesque dans les ann\u00e9es \u00e0 venir&nbsp;? C\u2019est en tout cas <a><\/a>\u00ab&nbsp;un chantier \u00e9norme, sur lequel il y a un r\u00e9el consensus de toutes les parties pour entamer des changements de fond&nbsp;\u00bb, conclut Alain Kaufmann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clap de fin pour les patients perdus dans la jungle des soins ? Pas encore. Mais des \u00e9volutions vers le partenariat dans le domaine de la sant\u00e9 se font toujours plus fortes, comme le montrent deux \u00e9tudes men\u00e9es par le ColLaboratoire.<\/p>\n","protected":false},"author":1002047,"featured_media":3937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[9,109],"tags":[],"class_list":{"0":"post-5225","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-recherche","8":"category-sante"},"uagb_featured_image_src":{"full":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",1200,700,false],"thumbnail":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL-150x150.jpeg",150,150,true],"medium":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL-300x175.jpeg",300,175,true],"medium_large":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL-768x448.jpeg",580,338,true],"large":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL-1024x597.jpeg",580,338,true],"1536x1536":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",1200,700,false],"2048x2048":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",1200,700,false],"post-thumbnail":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",1200,700,false],"chaplin_preview_image_low_resolution":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL-540x315.jpeg",540,315,true],"chaplin_preview_image_high_resolution":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL-1080x630.jpeg",1080,630,true],"chaplin_fullscreen":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",1200,700,false],"gform-image-choice-sm":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",300,175,false],"gform-image-choice-md":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",400,233,false],"gform-image-choice-lg":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",600,350,false],"mailpoet_newsletter_max":["https:\/\/wp.unil.ch\/uniscope\/files\/2021\/11\/Alain-Kaufmann-directeur-du-ColLaboratoire-de-lUNIL.-David-Trotta-\u00a9-UNIL.jpeg",1200,700,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/wp.unil.ch\/uniscope\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Clap de fin pour les patients perdus dans la jungle des soins ? Pas encore. Mais des \u00e9volutions vers le partenariat dans le domaine de la sant\u00e9 se font toujours plus fortes, comme le montrent deux \u00e9tudes men\u00e9es par le ColLaboratoire.","_links":{"self":[{"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/posts\/5225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/users\/1002047"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/comments?post=5225"}],"version-history":[{"count":1,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/posts\/5225\/revisions"}],"predecessor-version":[{"id":9603,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/posts\/5225\/revisions\/9603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/media\/3937"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/media?parent=5225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/categories?post=5225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/uniscope\/wp-json\/wp\/v2\/tags?post=5225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}