{"id":215,"date":"2017-08-29T10:50:08","date_gmt":"2017-08-29T08:50:08","guid":{"rendered":"http:\/\/wp.unil.ch\/tolerance\/2017\/08\/affiche-pour-les-conferences-publiques-du-semestre-dautomne-2017\/"},"modified":"2017-08-29T10:51:44","modified_gmt":"2017-08-29T08:51:44","slug":"affiche-pour-les-conferences-publiques-du-semestre-dautomne-2017","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/tolerance\/2017\/08\/affiche-pour-les-conferences-publiques-du-semestre-dautomne-2017\/","title":{"rendered":"Affiche pour les conf\u00e9rences publiques du semestre d&#8217;automne 2017"},"content":{"rendered":"<p>Vous pouvez t\u00e9l\u00e9charger l&#8217;affiche des conf\u00e9rences publiques du semestre d&#8217;automne 2017\u00a0<a href=\"https:\/\/wp.unil.ch\/tolerance\/files\/2017\/08\/AfficheTolerance2017A.pdf\">ici.<\/a><\/p>\n<p><a href=\"https:\/\/wp.unil.ch\/tolerance\/files\/2017\/08\/AfficheTolerance2017A.pdf\">AfficheTolerance2017A<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous pouvez t\u00e9l\u00e9charger l&#8217;affiche des conf\u00e9rences publiques du semestre d&#8217;automne 2017\u00a0ici. AfficheTolerance2017A<\/p>\n","protected":false},"author":1001500,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-215","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/posts\/215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/users\/1001500"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/posts\/215\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/media?parent=215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/categories?post=215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/tolerance\/wp-json\/wp\/v2\/tags?post=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}