{"id":1432,"date":"2020-11-25T16:22:54","date_gmt":"2020-11-25T15:22:54","guid":{"rendered":"https:\/\/wp.unil.ch\/narratologie\/?p=1432"},"modified":"2020-11-25T16:25:52","modified_gmt":"2020-11-25T15:25:52","slug":"creativite-et-emergence-iconique-images-histoire-narrations-annonce-de-colloque-en-ligne","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/narratologie\/2020\/11\/creativite-et-emergence-iconique-images-histoire-narrations-annonce-de-colloque-en-ligne\/","title":{"rendered":"Cr\u00e9ativit\u00e9 et \u00e9mergence iconique : images, histoire, narrations (annonce de colloque en ligne)"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/unice.fr\/laboratoires\/lirces\/fr\/contenus-riches\/evenements-1\/colloque-creativite-et-emergence-iconique-images-histoire-narrations\">Le Colloque \u00ab Cr\u00e9ativit\u00e9 et \u00e9mergence iconique : images, histoire, narrations \u00bb<\/a> est organis\u00e9 par le LIRCES UPR 3159 et EUR CREATES, Universit\u00e9 C\u00f4te d\u2019Azur et CRC, \u00c9cole des Mines Paris-Tech :\u00a0<br>Franck Guarnieri, Marc Marti, C\u00e9line Masoni.\u00a0<\/strong><\/p>\n\n\n\n<p><strong>10 et 11 d\u00e9cembre 2020<\/strong><\/p>\n\n\n\n<p>Inscriptions: le colloque se tenant sous ZOOM, merci d&rsquo;envoyer votre inscription pour recevoir le lien de connexion en \u00e9crivant \u00e0\u00a0<a rel=\"noreferrer noopener\" href=\"mailto:Marc.MARTI@univ-cotedazur.fr\" target=\"_blank\">Marc.MARTI@univ-cotedazur.fr<\/a>\u00a0ou\u00a0<a rel=\"noreferrer noopener\" href=\"mailto:Celine.MASONI-LACROIX@univ-cotedazur.fr\" target=\"_blank\">Celine.MASONI-LACROIX@univ-cotedazur.fr<\/a>\u00a0<\/p>\n\n\n\n<p><strong>Il s&rsquo;agit d&rsquo;un projet financ\u00e9 par le programme UCA-JEDI\u00a0ANR-15-IDEX-01.<\/strong><\/p>\n\n\n\n<p>L\u2019image, des lettres aux arts, des sciences humaines et sociales aux sciences de l\u2019ing\u00e9nieur, est un objet de recherche n\u00e9cessairement interdisciplinaire. Du sch\u00e9ma scientifique \u00e0 l\u2019\u0153uvre d\u2019art iconographique, audiovisuelle, vid\u00e9oludique, elle est un des supports privil\u00e9gi\u00e9s de la cr\u00e9ativit\u00e9 humaine, appr\u00e9hend\u00e9e dans son sens le plus large. Sans cesse r\u00e9invent\u00e9e et r\u00e9interpr\u00e9t\u00e9e, elle est le t\u00e9moin de nouveaux modes de pens\u00e9e et d\u2019action, de leur inscription dans le temps et de leur \u00e9mergence dans tous les champs de la connaissance. L\u2019image est loin d\u2019avoir un simple rapport analogique avec la pens\u00e9e ou le r\u00e9el. En effet, elle poss\u00e8de aussi une capacit\u00e9 \u00e0 d\u00e9clencher la narration en \u00e9troite relation avec son contexte culturel, dans lequel sont immerg\u00e9s producteur et spectateur, gr\u00e2ce aussi \u00e0 sa capacit\u00e9 \u00e0 mobiliser des st\u00e9r\u00e9otypes relevant de l\u2019imaginaire social, ainsi qu\u2019\u00e0 la fa\u00e7on dont l\u2019image les donne \u00e0 voir et les repr\u00e9sente. Elle peut \u00eatre aussi, en ce sens, un facilitateur de la cognition sociale.<\/p>\n\n\n\n<p><a href=\"https:\/\/unice.fr\/laboratoires\/lirces\/fr\/contenus-riches\/evenements-1\/colloque-creativite-et-emergence-iconique-images-histoire-narrations\/leadImage\/image_view_fullscreen\">T\u00e9l\u00e9charger le programme<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Colloque \u00ab Cr\u00e9ativit\u00e9 et \u00e9mergence iconique : images, histoire, narrations \u00bb est organis\u00e9 par le LIRCES UPR 3159 et EUR CREATES, Universit\u00e9 C\u00f4te d\u2019Azur et CRC, \u00c9cole des Mines Paris-Tech :\u00a0Franck Guarnieri, Marc Marti, C\u00e9line Masoni.\u00a0 10 et 11<\/p>\n","protected":false},"author":1001953,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-1432","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/posts\/1432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/users\/1001953"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/comments?post=1432"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/posts\/1432\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/media?parent=1432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/categories?post=1432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/narratologie\/wp-json\/wp\/v2\/tags?post=1432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}