{"id":2144,"date":"2016-04-07T12:36:48","date_gmt":"2016-04-07T10:36:48","guid":{"rendered":"http:\/\/wp.unil.ch\/geoblog\/?p=2144"},"modified":"2018-08-03T11:55:38","modified_gmt":"2018-08-03T09:55:38","slug":"reseaux-spatiaux-modeles-classification-et-flux","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/geoblog\/2016\/04\/reseaux-spatiaux-modeles-classification-et-flux\/","title":{"rendered":"R\u00e9seaux spatiaux : mod\u00e8les, classification et flux"},"content":{"rendered":"<p><em>Th\u00e8se soutenue par Guillaume Guex le 7 avril 2016, Institut de g\u00e9ographie et durabilit\u00e9 (IGD)<\/em><\/p>\n<p>Un r\u00e9seau spatial est une structure constitu\u00e9e d\u2019objets appel\u00e9s noeuds, localis\u00e9s dans l\u2019espace, et poss\u00e9dant des connexions de diff\u00e9rentes nature appel\u00e9es ar\u00eates. Cette d\u00e9finition comprend un large panel de structures. Les r\u00e9seaux routiers, a\u00e9riens, ferroviaires, de lignes \u00e9lectriques, de rivi\u00e8res, etc. ne sont que quelques exemples de r\u00e9seaux spatiaux que nous c\u00f4toyons tous les jours. <!--more--><\/p>\n<p>Contrairement aux r\u00e9seaux usuels, qui ne poss\u00e8dent pas de composante spatiale, maintenir une connexion entre deux noeuds d\u2019un r\u00e9seau spatial requiert un co\u00fbt qui va d\u00e9pendre de la distance s\u00e9parant ces noeuds, et la structure du r\u00e9seau tout enti\u00e8re est alors intimement li\u00e9e \u00e0 l&rsquo;espace. L&rsquo;analyse du rapport existant entre l\u2019espace et la structure du r\u00e9seau n\u2019est pas chose ais\u00e9e et les approches permettant d\u2019y arriver sont nombreuses. Ce travail se concentre sur la cr\u00e9ation de mod\u00e8les math\u00e9matiques facilitant cet objectif, en particulier \u00e0 l&rsquo;aide de mod\u00e8les de flux.<\/p>\n<p>Un flux peut \u00eatre interpr\u00e9t\u00e9 comme une quantit\u00e9 de mati\u00e8re cr\u00e9\u00e9e par un certain nombre de noeuds appel\u00e9s sources, naviguant sur les ar\u00eates du r\u00e9seaux pour finalement \u00eatre absorb\u00e9e par d\u2019autres noeuds, appel\u00e9s cibles. Le comportement adopt\u00e9 par le flux lors de sa navigation est g\u00e9n\u00e9ralement dict\u00e9 par la minimisation d\u2019une fonction, et en choisissant judicieusement cette derni\u00e8re, il est possible d\u2019obtenir des flux permettant une exploration particuli\u00e8re de la structure du r\u00e9seau. L\u2019ingr\u00e9dient principal de cette th\u00e8se sera un mod\u00e8le de flux in\u00e9dit, appel\u00e9 le flux de transport randomis\u00e9. Ce flux, dont le comportement peut \u00eatre ajust\u00e9 par un param\u00e8tre, est \u00e0 la crois\u00e9e entre le flux de transport optimal et le flux al\u00e9atoire. Lorsque le param\u00e8tre est bas, ce flux permettra de transporter la mati\u00e8re dont il est constitu\u00e9 des sources jusqu\u2019aux cibles en minimisant les co\u00fbts.<\/p>\n<p>A l\u2019oppos\u00e9, lorsque le param\u00e8tre est \u00e9lev\u00e9, ce flux suivra une marche al\u00e9atoire, explorant la totalit\u00e9 du r\u00e9seau avant d\u2019\u00eatre absorb\u00e9. Ces deux extr\u00eames contiennent des flux qui ont \u00e9t\u00e9 \u00e9tudi\u00e9s dans la litt\u00e9rature, mais nous verrons ici que lorsque la temp\u00e9rature est interm\u00e9diaire, le flux de transport randomis\u00e9 adoptera alors un comportement in\u00e9dit, permettant d\u2019appr\u00e9hender la structure du r\u00e9seau de mani\u00e8re plus compl\u00e8te. Ce flux nous permettra de construire de nouveaux indices de centralit\u00e9, de nouvelles dissimilarit\u00e9s et offrira une solution num\u00e9rique efficiente \u00e0 la r\u00e9solution du probl\u00e8me de transport optimal dans un r\u00e9seau.<\/p>\n<p>Ce nouvel objet soul\u00e8vera \u00e9galement quelques questions fondamentales, d\u00e9passant largement le cadre des r\u00e9seaux spatiaux. Un chapitre sur la cr\u00e9ation de mod\u00e8les de r\u00e9seaux spatiaux, similaires aux r\u00e9seaux existants, viendra compl\u00e9ter l\u2019analyse obtenue par les flux. Si le flux permet, entre autres, d\u2019obtenir de l\u2019information sur la position des noeuds dans l\u2019espace gr\u00e2ce \u00e0 la structure du r\u00e9seau, ce dernier chapitre bouclera la boucle en faisant le travail en sens inverse : d\u00e9duire l\u2019information sur la structure d\u2019un graphe spatial \u00e0 partir de la position des noeuds dans l\u2019espace.<\/p>\n<p>Cette th\u00e8se, constitu\u00e9e d\u2019articles \u201cpeer-reviewed\u201d ins\u00e9r\u00e9s au milieu d\u2019un manuscrit r\u00e9dig\u00e9 \u00e0 la suite de ceux-ci, pr\u00e9sente deux niveaux de lecture. En lisant le manuscrit, un lecteur pourra comprendre les enjeux, le contexte et la probl\u00e9matique de notre approche sur l\u2019analyse des r\u00e9seaux spatiaux, tout en se familiarisant avec le formalisme. Cette lecture s\u2019adresse ainsi \u00e0 un large public, cependant familier avec les notations math\u00e9matiques. La lecture des articles, moins accessible, pr\u00e9sente la r\u00e9alit\u00e9 du travail scientifique accompli durant cinq ann\u00e9es. Ces articles ne seront pas toujours parfaitement coh\u00e9rents les uns par rapport aux autres, et les id\u00e9es expos\u00e9es \u00e9voluent au fil du temps. N\u00e9anmoins, leur lecture permet d\u2019avoir les d\u00e9monstrations et les r\u00e9sultats les plus significatifs, compl\u00e9tant ainsi le contexte donn\u00e9 par le manuscrit sous la forme d\u2019avanc\u00e9es faites dans le domaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Th\u00e8se soutenue par Guillaume Guex le 7 avril 2016, Institut de g\u00e9ographie et durabilit\u00e9 (IGD) Un r\u00e9seau spatial est une structure constitu\u00e9e d\u2019objets appel\u00e9s noeuds, localis\u00e9s dans l\u2019espace, et poss\u00e9dant des connexions de diff\u00e9rentes nature appel\u00e9es ar\u00eates. Cette d\u00e9finition comprend un large panel de structures. Les r\u00e9seaux routiers, a\u00e9riens, ferroviaires, de lignes \u00e9lectriques, de rivi\u00e8res, [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":3358,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[49465],"tags":[],"class_list":{"0":"post-2144","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-theses-soutenues"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/posts\/2144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/comments?post=2144"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/posts\/2144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/media\/3358"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/media?parent=2144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/categories?post=2144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/geoblog\/wp-json\/wp\/v2\/tags?post=2144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}