{"id":872,"date":"2019-10-21T16:59:21","date_gmt":"2019-10-21T14:59:21","guid":{"rendered":"http:\/\/wp.unil.ch\/futurspossibles\/?p=872"},"modified":"2019-12-03T14:20:19","modified_gmt":"2019-12-03T13:20:19","slug":"podcast-2-entretien-avec-jacques-dubochet","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/futurspossibles\/2019\/10\/podcast-2-entretien-avec-jacques-dubochet\/","title":{"rendered":"Podcast #2 : Entretien avec Jacques Dubochet"},"content":{"rendered":"<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-873 \" src=\"https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-1024x768.jpg\" alt=\"\" width=\"655\" height=\"491\" srcset=\"https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-1024x768.jpg 1024w, https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-300x225.jpg 300w, https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-768x576.jpg 768w, https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-1320x990.jpg 1320w, https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124.jpg 1600w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-872-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/podcast.unil.ch\/podcast\/unil\/futurspossibles\/dubochet.mp3?_=1\" \/><a href=\"https:\/\/podcast.unil.ch\/podcast\/unil\/futurspossibles\/dubochet.mp3\">https:\/\/podcast.unil.ch\/podcast\/unil\/futurspossibles\/dubochet.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p>D\u00e9but octobre 2017, la nouvelle nous arrivait \u00e0 Lausanne : le comit\u00e9 Nobel annon\u00e7ait que Jacques Dubochet allait recevoir avec l&rsquo;am\u00e9ricain Joachim Frank et le britannique Richard Henderson, le prix Nobel de chimie pour ses travaux en cryo-microscopie \u00e9lectronique. Jacques, engag\u00e9 depuis de nombreuses ann\u00e9es pour des causes qui lui tiennent \u00e0 c\u0153ur, notamment les rapports sciences soci\u00e9t\u00e9, le r\u00f4le des chercheurs, la durabilit\u00e9\u2026devient une voix ! Jacques Dubochet s\u2019exprime et participe de mani\u00e8re tr\u00e8s engag\u00e9e au \u00ab mouvement \u00bb qui anime beaucoup la jeunesse pour faire face aux enjeux climatiques. C\u2019est donc tout naturellement qu\u2019on avait envie d\u2019entendre \u00ab sa voix \u00bb dans le cadre des r\u00e9flexions men\u00e9es \u00e0 l\u2019occasion du cycle Imaginaires des futurs possibles. Il nous donne sa vision de l&rsquo;histoire de l&rsquo;humain face \u00e0 ces enjeux en trois actes.<\/p>\n<h5><strong>Podcasts :<\/strong><\/h5>\n<a href=\"https:\/\/podcasts.apple.com\/podcast\/id1489696906\" class=\"su-button su-button-style-soft\" style=\"color:#FFFFFF;background-color:#838382;border-color:#696968;border-radius:0px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 20px;font-size:16px;line-height:32px;border-color:#a9a9a8;border-radius:0px;text-shadow:none\"> Je m&rsquo;abonne !<\/span><\/a>\n","protected":false},"excerpt":{"rendered":"<p>Jacques Dubochet, prix Nobel de chimie 2017, nous parle d\u2019engagement pour le climat et le vivant, d\u2019une pi\u00e8ce en trois actes, et nous conte le r\u00e9cit de futurs possibles.<\/p>\n","protected":false},"author":1119,"featured_media":873,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[22,4],"tags":[],"class_list":{"0":"post-872","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-podcast","8":"category-contributions"},"uagb_featured_image_src":{"full":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124.jpg",1600,1200,false],"thumbnail":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-150x150.jpg",150,150,true],"medium":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-300x225.jpg",300,225,true],"medium_large":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-768x576.jpg",735,551,true],"large":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-1024x768.jpg",735,551,true],"1536x1536":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124.jpg",1536,1152,false],"2048x2048":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124.jpg",1600,1200,false],"hitmag-landscape":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-1120x450.jpg",1120,450,true],"hitmag-featured":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-735x400.jpg",735,400,true],"hitmag-grid":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-348x215.jpg",348,215,true],"hitmag-list":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-290x220.jpg",290,220,true],"hitmag-thumbnail":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-135x93.jpg",135,93,true],"mailpoet_newsletter_max":["https:\/\/wp.unil.ch\/futurspossibles\/files\/2019\/10\/IMG_1124-1320x990.jpg",1320,990,true]},"uagb_author_info":{"display_name":"Delphine Ducoulombier","author_link":"https:\/\/wp.unil.ch\/futurspossibles\/author\/dducoulo\/"},"uagb_comment_info":0,"uagb_excerpt":"Jacques Dubochet, prix Nobel de chimie 2017, nous parle d\u2019engagement pour le climat et le vivant, d\u2019une pi\u00e8ce en trois actes, et nous conte le r\u00e9cit de futurs possibles.","_links":{"self":[{"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/posts\/872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/users\/1119"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/comments?post=872"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/posts\/872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/media\/873"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/media?parent=872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/categories?post=872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/futurspossibles\/wp-json\/wp\/v2\/tags?post=872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}