{"id":9342,"date":"2025-01-24T14:44:11","date_gmt":"2025-01-24T13:44:11","guid":{"rendered":"https:\/\/wp.unil.ch\/esspace\/?p=9342"},"modified":"2025-01-28T10:53:50","modified_gmt":"2025-01-28T09:53:50","slug":"situation-de-no-deal-avec-wiley-et-lww","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/esspace\/2025\/01\/situation-de-no-deal-avec-wiley-et-lww\/","title":{"rendered":"Situation de \u00ab\u00a0No Deal\u00a0\u00bb\u00a0avec Wiley et LWW"},"content":{"rendered":"\n<p><strong>Les n\u00e9gociations \u00ab&nbsp;Big Deal&nbsp;\u00bb<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/wp.unil.ch\/esspace\/files\/2025\/01\/No_Deal.jpg\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"220\" src=\"https:\/\/wp.unil.ch\/esspace\/files\/2025\/01\/No_Deal.jpg\" alt=\"\" class=\"wp-image-9429\" \/><\/a><figcaption class=\"wp-element-caption\">\u00a9 Gorshkov13 | Dreamstime.com <\/figcaption><\/figure>\n<\/div>\n\n\n<p>Depuis 2018, sous <a href=\"https:\/\/www.swissuniversities.ch\/fileadmin\/swissuniversities\/Dokumente\/Hochschulpolitik\/Open_Access\/2023_swissuniversities_BDN_aims_and_governance.pdf\">mandat<\/a> de Swissuniversities, le Consortium des biblioth\u00e8ques universitaires suisses (CSAL) m\u00e8ne des n\u00e9gociations strat\u00e9giques, appel\u00e9es \u00ab Big Deals \u00bb, avec les \u00e9diteurs Springer Nature, Wiley et Elsevier, qui repr\u00e9sentent environ trois quarts des licences en Suisse. Agissant pour le compte de plus de 40 institutions nationales, le consortium vise \u00e0 renforcer la position de la Suisse \u00e0 l\u2019international en d\u00e9fendant un acc\u00e8s \u00e9quitable et durable aux publications acad\u00e9miques pour les institutions de recherche. Le mandat de n\u00e9gociation pr\u00e9voit notamment l\u2019acc\u00e8s (read access rights) aux titres de ces \u00e9diteurs, la mise en place d\u2019une neutralit\u00e9 des co\u00fbts au niveau national, des m\u00e9canismes de contr\u00f4le des d\u00e9penses pour l\u2019Open Access, des mod\u00e8les tarifaires structur\u00e9s pour le Gold OA et l\u2019Hybride OA, ou encore l\u2019adoption d\u2019une licence CC BY comme standard pour les publications.<\/p>\n\n\n\n<p>\u00c9chelonn\u00e9es dans le temps, les n\u00e9gociations Big Deal ont commenc\u00e9 avec un premier cycle en 2018 avec Springer Nature et se sont poursuivies en 2024 avec un deuxi\u00e8me cycle de n\u00e9gociations avec Elsevier et Wiley. Parmi l\u2019\u00e9quipe de d\u00e9l\u00e9gation suisse de n\u00e9gociation qui depuis le printemps 2024 m\u00e8ne des n\u00e9gociations avec Wiley, le Professeur Jo\u00ebl Billieux, de l\u2019IP est un des deux repr\u00e9sentants de la communaut\u00e9 des chercheurs et chercheuses pour Swissuniversities. Engag\u00e9 depuis de nombreuses ann\u00e9es dans la promotion des pratiques d\u2019Open Science (dont l\u2019OpenAccess n\u2019est qu\u2019une des facettes), il joue un r\u00f4le actif dans la d\u00e9fense des int\u00e9r\u00eats de la communaut\u00e9 acad\u00e9mique suisse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Situation de \u00ab&nbsp;no deal&nbsp;\u00bb&nbsp;d\u00e8s le 1er janvier 2025<\/h2>\n\n\n\n<p>En fin d\u2019ann\u00e9e 2024, aucun accord satisfaisant n\u2019a \u00e9t\u00e9 encore trouv\u00e9 pour les revues scientifiques hybrides et en Gold OA chez Wiley (voir <a href=\"https:\/\/www.swissuniversities.ch\/fr\/themes\/open-science\/negociations-avec-les-editeurs\/wiley\" target=\"_blank\" rel=\"noreferrer noopener\">communication de Swissuniversities)<\/a>&nbsp;&nbsp;et chez Lippincott Williams and Wilkins (LWW) (voir la <a href=\"https:\/\/consortium.ch\/type-produkt\/lippincott-williams-wilkins-lww\/?lang=fr\" target=\"_blank\" rel=\"noreferrer noopener\">communication du CSAL<\/a>) menant \u00e0 une situation de \u00ab&nbsp;no deal&nbsp;\u00bb d\u00e8s le 1er janvier 2025. Bien que cette situation pose des d\u00e9fis pour la communaut\u00e9 de chercheurs et chercheuses, elle constitue un levier de pression consid\u00e9rable visant \u00e0 obtenir un accord satisfaisant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment puis-je acc\u00e9der \u00e0 un article publi\u00e9 chez ces \u00e9diteurs ?<\/h2>\n\n\n\n<p>Les contenus publi\u00e9s \u00e0 partir du 1er janvier 2025 ne seront plus accessibles, sauf s\u2019ils sont disponibles en Open Access. Pour obtenir un article, le <a href=\"https:\/\/www.swissuniversities.ch\/fileadmin\/swissuniversities\/Dokumente\/Hochschulpolitik\/Open_Access\/20241213_how_to_get_the_article.pdf\">CSAL et Swissuniversitires<\/a> recommandent la recherche d&rsquo;articles dans leur version Open Access, facilit\u00e9e par l&rsquo;installation dans les navigateurs Firefox ou Chrome de \u00ab\u202fboutons\u202f\u00bb\u202fde recherche (<a href=\"https:\/\/unpaywall.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Unpaywall<\/a>, <a href=\"https:\/\/openaccessbutton.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Open Access Button<\/a> ou <a href=\"https:\/\/core.ac.uk\/services\/discovery\" target=\"_blank\" rel=\"noreferrer noopener\">Core Discovery<\/a>), la recherche de versions disponibles sur les plateformes institutionnelles (e.g. <a href=\"https:\/\/serval.unil.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Serval<\/a>, <a href=\"https:\/\/orfee.hepl.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Orphee<\/a>) ou une demande de copie directement aupr\u00e8s des auteurs et autrices de correspondance, par courriel ou via des plateformes telles que &nbsp;ResearchGate.&nbsp;<\/p>\n\n\n\n<p>La BCUL se tient \u00e9galement \u00e0 votre disposition pour vous aider dans votre recherche \u00e0 travers les services suivants\u202f:\u202f&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les abonnements papier disponibles sur nos sites BCUL&nbsp;&nbsp;<\/li>\n\n\n\n<li>L\u2019acc\u00e8s \u00e9lectronique\u202fpour les revues jusqu\u2019en fin 2024.&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.bcu-lausanne.ch\/pret-et-consultation\/?id=pretentrebibliotheques\" target=\"_blank\" rel=\"noreferrer noopener\">Le pr\u00eat entre biblioth\u00e8ques (PEB)<\/a>&nbsp;<\/li>\n\n\n\n<li>Le guichet d\u2019information de votre site BCUL&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/question.bcu-lausanne.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Le service questions\/r\u00e9ponses de la BCUL<\/a>&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment puis-je publier un article chez ces \u00e9diteurs ?<\/h2>\n\n\n\n<p>Les chercheurs et chercheuses conservent la libert\u00e9 de choisir une revue de ces maisons d\u2019\u00e9dition et de soumettre leurs manuscrits selon le processus classique, c\u2019est-\u00e0-dire sans recours \u00e0 l\u2019Open Access. En effet, en l\u2019absence d\u2019un accord en vigueur avec ces \u00e9diteurs, aucun quota pour l\u2019Open Access (OA) n\u2019est disponible \u00e0 l\u2019UNIL. Par cons\u00e9quent, les frais li\u00e9s une publication en OA ne pourront pas \u00eatre couverts par l\u2019UNIL et devront le cas \u00e9ch\u00e9ant \u00eatre directement assum\u00e9s directement par les auteur\u00b7es. De plus, pour cette m\u00eame raison, l\u2019UNIL ne finance pas les frais de publication en Open Access (Gold OA) aupr\u00e8s de ces \u00e9diteurs via son fonds de soutien. Ainsi, les articles soumis par voie traditionnelle dans des revues payantes ou des revues hybrides chez Wiley et LWW ne seront pas accessibles pour les chercheurs et les chercheuses appartenant \u00e0 des institutions faisant partie du CSAL, dont l\u2019UNIL, et cela pendant toute la p\u00e9riode du No Deal.\u00a0\u00a0<\/p>\n\n\n\n<p>Dans un tel contexte, L\u2019UNIL recommande de s\u2019abstenir de soumettre des articles et\/ou de payer des frais pour des publication en OA chez ces \u00e9diteurs pendant la phase de n\u00e9gociation en cours, afin de pr\u00e9server le \u00ab pouvoir de n\u00e9gociation \u00bb vis-\u00e0-vis de ces \u00e9diteurs.<\/p>\n\n\n\n<p><em>Equipe IRIS, service de la recherche UNIL<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les n\u00e9gociations \u00ab&nbsp;Big Deal&nbsp;\u00bb<\/p>\n","protected":false},"author":1001335,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_uag_custom_page_level_css":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[9912],"tags":[],"class_list":["post-9342","post","type-post","status-publish","format-standard","category-politique-de-la-recherche"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"hitmag-landscape":false,"hitmag-featured":false,"hitmag-grid":false,"hitmag-list":false,"hitmag-thumbnail":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false,"mailpoet_newsletter_max":false},"uagb_author_info":{"display_name":"Oana Barsin","author_link":"https:\/\/wp.unil.ch\/esspace\/author\/obarsin\/"},"uagb_comment_info":0,"uagb_excerpt":"Les n\u00e9gociations \u00ab&nbsp;Big Deal&nbsp;\u00bb","_links":{"self":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts\/9342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/users\/1001335"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/comments?post=9342"}],"version-history":[{"count":5,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts\/9342\/revisions"}],"predecessor-version":[{"id":9512,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts\/9342\/revisions\/9512"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/media?parent=9342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/categories?post=9342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/tags?post=9342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}