{"id":4403,"date":"2020-05-29T09:34:23","date_gmt":"2020-05-29T07:34:23","guid":{"rendered":"http:\/\/wp.unil.ch\/esspace\/?p=4403"},"modified":"2020-06-05T12:01:55","modified_gmt":"2020-06-05T10:01:55","slug":"cause-commune-une-methodologie-daction-recherche","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/esspace\/2020\/05\/cause-commune-une-methodologie-daction-recherche\/","title":{"rendered":"Cause Commune : une m\u00e9thodologie d\u2019action-recherche"},"content":{"rendered":"<p>Ce projet d\u2019action-recherche communautaire et participative est fond\u00e9 sur un principe de collaboration entre chercheur\u00b7e\u00b7s du Centre LIVES \u00e0 l\u2019UNIL et des professionnel\u00b7le\u00b7s du service de la coh\u00e9sion sociale de la commune de Chavannes-pr\u00e8s-Renens (CPR). Cette intervention vise une am\u00e9lioration de la qualit\u00e9 sociale dans les quartiers et de la sant\u00e9 publique \u00e0 Chavannes et le d\u00e9veloppement d\u2019une m\u00e9thodologie innovante \u00e0 la fois participative, interg\u00e9n\u00e9rationnelle et inter-, voire trans-disciplinaire.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/wp.unil.ch\/esspace\/files\/2020\/05\/Spini_gd.jpg\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4471 alignleft\" src=\"https:\/\/wp.unil.ch\/esspace\/files\/2020\/05\/Spini_gd-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/wp.unil.ch\/esspace\/files\/2020\/05\/Spini_gd-300x225.jpg 300w, https:\/\/wp.unil.ch\/esspace\/files\/2020\/05\/Spini_gd.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Il est port\u00e9 par le Prof. <strong>Dario Spini<\/strong>, de l\u2019Universit\u00e9 de Lausanne, une coordinatrice charg\u00e9e de projet <strong>Emmanuelle Anex<\/strong> et du c\u00f4t\u00e9 de CPR, par <strong>Alain Plattet<\/strong>, directeur du service de la coh\u00e9sion sociale et par <strong>Monique Chevallay Piguet<\/strong>, coordinatrice. D\u2019autres professeur\u00b7e\u00b7s et chercheur\u00b7e\u00b7s de l\u2019UNIL, notamment de SSP, de la HES-SO et de l\u2019EPFL sont \u00e9galement impliqu\u00e9\u00b7e\u00b7s.<\/p>\n<p>La commune de CPR va faire face ces prochaines ann\u00e9es \u00e0 des d\u00e9fis majeurs : doublement de sa population en quelques ann\u00e9es et diversification de celle-ci (en termes d\u2019\u00e2ges, de profils socio-\u00e9conomiques et d\u2019origines \u00ab\u00a0ethniques\u00a0\u00bb); ayant pour cons\u00e9quences diff\u00e9rents risques \u2013 une individualisation de la soci\u00e9t\u00e9 et une communautarisation pouvant cr\u00e9er des conflits entre groupes sociaux (origines ethnique, g\u00e9n\u00e9rations, etc.), d\u00e9saffiliation et isolement. Seniors, jeunes, familles d\u00e9plorent d\u2019ailleurs un manque d\u2019identit\u00e9, de coh\u00e9sion et d\u2019int\u00e9gration. Ces risques sont \u00e9galement \u00e0 la base du projet qui vise \u00e0 renforcer la politique d\u2019action sociale communale et \u00ab\u00a0d\u2019habiter la ville\u00a0\u00bb de mani\u00e8re plus int\u00e9grative en prenant la mixit\u00e9 sociale et g\u00e9n\u00e9rationnelle comme ressources, plut\u00f4t que comme probl\u00e8mes.<\/p>\n<p>Le projet est planifi\u00e9 de mani\u00e8re cyclique sur trois ann\u00e9es correspondant \u00e0 trois zones d\u2019intervention distinctes. L\u2019objectif du projet est double. Premi\u00e8rement, l\u2019action sociale doit viser un renforcement de la coh\u00e9sion et de l\u2019int\u00e9gration sociale, et un accroissement de la capacit\u00e9 d\u2019agir collective des habitant\u00b7e\u00b7s \u2013 et par ce biais, nous faisons l\u2019hypoth\u00e8se que cela aura un effet positif \u00e9galement sur la sant\u00e9 psychique et physique. Comment\u00a0? En cr\u00e9ant du lien social gr\u00e2ce \u00e0 des projets men\u00e9s par et avec les habitant\u00b7e\u00b7s sur des th\u00e9matiques qui les concernent\u00a0; le tissu social va se renforcer et se diversifier et amener l\u2019effet boule de neige attendu. Deuxi\u00e8mement, la d\u00e9marche d\u2019action-recherche mise en place doit inviter au d\u00e9cloisonnement des pratiques, des approches, des savoirs et savoir-faire des professionnel\u00b7le\u00b7s, des responsables politiques, des chercheur\u00b7e\u00b7s et des habitant\u00b7e\u00b7s, ce qui pourrait transformer \u00e0 terme les conditions d\u2019une citoyennet\u00e9 dite participative.<\/p>\n<p>Tout au long du projet et \u00e0 l\u2019issue de celui-ci, la d\u00e9marche, les r\u00e9sultats et les bonnes pratiques seront largement communiqu\u00e9s\u00a0; l\u2019objectif \u00e9tant de cr\u00e9er une soci\u00e9t\u00e9 plus r\u00e9siliente, le partage des connaissances est primordial.<\/p>\n<p><em>Prof. Dario Spini et Emmanuelle Anex<br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce projet d\u2019action-recherche communautaire et participative est fond\u00e9 sur un principe de collaboration entre chercheur\u00b7e\u00b7s du Centre LIVES \u00e0 l\u2019UNIL et des professionnel\u00b7le\u00b7s du service de la coh\u00e9sion sociale de &hellip; <\/p>\n","protected":false},"author":1001335,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_uag_custom_page_level_css":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[9911],"tags":[],"class_list":["post-4403","post","type-post","status-publish","format-standard","category-science-et-societe"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"hitmag-landscape":false,"hitmag-featured":false,"hitmag-grid":false,"hitmag-list":false,"hitmag-thumbnail":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false,"mailpoet_newsletter_max":false},"uagb_author_info":{"display_name":"Oana Barsin","author_link":"https:\/\/wp.unil.ch\/esspace\/author\/obarsin\/"},"uagb_comment_info":0,"uagb_excerpt":"Ce projet d\u2019action-recherche communautaire et participative est fond\u00e9 sur un principe de collaboration entre chercheur\u00b7e\u00b7s du Centre LIVES \u00e0 l\u2019UNIL et des professionnel\u00b7le\u00b7s du service de la coh\u00e9sion sociale de &hellip;","_links":{"self":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts\/4403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/users\/1001335"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/comments?post=4403"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/posts\/4403\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/media?parent=4403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/categories?post=4403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/esspace\/wp-json\/wp\/v2\/tags?post=4403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}