{"id":824,"date":"2016-04-21T15:50:59","date_gmt":"2016-04-21T13:50:59","guid":{"rendered":"http:\/\/wp.unil.ch\/cavousestegal\/?p=824"},"modified":"2016-04-21T16:07:35","modified_gmt":"2016-04-21T14:07:35","slug":"14-juin-2016-20-ans-de-la-loi-sur-legalite-entre-femmes-et-hommes","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/cavousestegal\/2016\/04\/14-juin-2016-20-ans-de-la-loi-sur-legalite-entre-femmes-et-hommes\/","title":{"rendered":"14 juin 2016\u00a0: 20 ans de la Loi sur l\u2019\u00e9galit\u00e9 entre femmes et hommes"},"content":{"rendered":"<h3>Le 1er juillet 1996, la loi f\u00e9d\u00e9rale sur l\u2019\u00e9galit\u00e9 entre femmes et hommes (<a href=\"https:\/\/www.leg.ch\/\" target=\"_blank\">LEg<\/a>) entrait en vigueur. Le Bureau de l\u2019\u00e9galit\u00e9 et le <a href=\"https:\/\/www.unil.ch\/ceg\/fr\/home.html\" target=\"_blank\">Centre en \u00e9tudes genre CEG<\/a> de l\u2019UNIL vous invitent \u00e0 f\u00eater cet anniversaire le 14 juin 2016, Journ\u00e9e nationale des femmes, autour d\u2019un spectacle et de deux tables rondes*. Intitul\u00e9 \u00ab\u00a0Egalit\u00e9 des droits &#8211; \u00e9galit\u00e9 r\u00e9elle\u00a0?\u00a0\u00bb, cet \u00e9v\u00e9nement rassemblera plusieurs personnalit\u00e9s, dont l\u2019ancienne conseill\u00e8re f\u00e9d\u00e9rale Ruth Dreifuss.<\/h3>\n<p><!--more--><\/p>\n<h4>L\u2019\u00e9galit\u00e9 en droit<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-828\" src=\"https:\/\/wp.unil.ch\/cavousestegal\/files\/2016\/04\/Gr\u00e8ve-des-femmes_manif-1024x768.jpg\" alt=\"Gr\u00e8ve des femmes_manif\" width=\"249\" height=\"191\" \/>Il y a 20 ans, la LEg entrait en vigueur. Cette loi faisait suite \u00e0 l\u2019inscription de l\u2019\u00e9galit\u00e9 entre femmes et hommes dans la Constitution f\u00e9d\u00e9rale, approuv\u00e9e par le peuple suisse\u2026 15 ans auparavant, le 14 juin 1981. Ce jour-l\u00e0, mandat a \u00e9t\u00e9 donn\u00e9 au l\u00e9gislateur de concr\u00e9tiser l\u2019\u00e9galit\u00e9, en particulier dans les domaines de la famille, de la formation et du travail. Notamment, le droit \u00e0 un salaire \u00e9gal pour un travail de valeur \u00e9gale a \u00e9t\u00e9 ancr\u00e9 dans la Constitution. Il aura fallu une longue lutte, culminant dans la gr\u00e8ve des femmes du 14 juin 1991, pour aboutir \u00e0 cette loi.<\/p>\n<h4>Pionni\u00e8res et regards historiques<\/h4>\n<p>Quels moments forts ont jalonn\u00e9 ce long parcours\u00a0? Une premi\u00e8re table ronde reviendra sur ces ann\u00e9es d\u2019engagement pour l\u2019\u00e9galit\u00e9 des droits, y compris dans les hautes \u00e9coles. Pendront part \u00e0 cette discussion Ruth Dreifuss, ancienne conseill\u00e8re f\u00e9d\u00e9rale, ainsi que d\u2019autres sp\u00e9cialistes, actrices et acteurs des milieux politique et acad\u00e9mique, dont Dominique Arlettaz, recteur de l\u2019UNIL.<\/p>\n<h4>Enjeux actuels de l\u2019\u00e9galit\u00e9<\/h4>\n<p>20 ans, c\u2019est aussi le temps de dresser un bilan et d\u2019interroger l\u2019avenir. Une seconde discussion nous permettra de faire le point sur les enjeux actuels de l\u2019\u00e9galit\u00e9, notamment dans le monde acad\u00e9mique. Y participeront des politiciennes, chercheurs, chercheuses et juristes. Vous trouverez la liste compl\u00e8te des participant\u00b7e\u00b7s, le programme et d\u2019autres informations sur <a href=\"https:\/\/www.unil.ch\/egalite\" target=\"_blank\">www.unil.ch\/egalite<\/a>.<\/p>\n<h4>L\u2019\u00e9galit\u00e9 en f\u00eate<\/h4>\n<p>Ces \u00e9changes seront pr\u00e9c\u00e9d\u00e9s du spectacle \u00ab\u00a0R\u00e9cits de femmes\u00a0\u00bb. C\u2019est donc tout naturellement que l\u2019\u00e9v\u00e9nement se d\u00e9roulera au <a href=\"https:\/\/wp.unil.ch\/grangededorigny\/\" target=\"_blank\">Th\u00e9\u00e2tre de la Grange de Dorigny<\/a> (de 13h30 \u00e0 18h). L\u2019entr\u00e9e sera gratuite et se fera sur inscription, ouverte d\u00e8s fin avril et jusqu\u2019au 27 mai. Nous nous r\u00e9jouissons de vous rencontrer lors de cet apr\u00e8s-midi de l\u2019\u00ab\u00a0\u00e9galit\u00e9 en f\u00eate\u00a0\u00bb\u00a0!<\/p>\n<ul>\n<li>Avec le soutien de la <a href=\"https:\/\/www.unil.ch\/plage\/fr\/home.html\">Plateforme en \u00e9tudes genre PlaGe<\/a>, du <a href=\"https:\/\/www.lives-nccr.ch\/\">PRN LIVES<\/a> et du <a href=\"https:\/\/garciaproject.eu\/\">projet GARCIA<\/a>.<\/li>\n<\/ul>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Le 1er juillet 1996, la loi f\u00e9d\u00e9rale sur l\u2019\u00e9galit\u00e9 entre femmes et hommes (LEg) entrait en vigueur. Le Bureau de l\u2019\u00e9galit\u00e9 et le Centre en \u00e9tudes genre CEG&hellip;<\/p>\n","protected":false},"author":1380,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[5,1],"tags":[],"class_list":{"0":"post-824","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-egalite","8":"category-tous-les-articles"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts\/824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/users\/1380"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/comments?post=824"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts\/824\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/media?parent=824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/categories?post=824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/tags?post=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}