{"id":469,"date":"2014-10-30T10:00:11","date_gmt":"2014-10-30T09:00:11","guid":{"rendered":"http:\/\/wp.unil.ch\/cavousestegal\/?p=469"},"modified":"2016-05-11T14:29:28","modified_gmt":"2016-05-11T12:29:28","slug":"mobilite-en-couple-ou-en-famille","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/cavousestegal\/2014\/10\/mobilite-en-couple-ou-en-famille\/","title":{"rendered":"Mobilit\u00e9 en couple ou en famille"},"content":{"rendered":"<h3>La mobilit\u00e9 scientifique en couple ou en famille a des implications pour l\u2019\u00e9galit\u00e9 des chances. Les initiatives du Bureau de l\u2019\u00e9galit\u00e9 vise \u00e0 aider les chercheur-e-s \u00e0 mieux pr\u00e9parer leur s\u00e9jour, tout en poursuivant un objectif d\u2019\u00e9galit\u00e9 dans leur couple.<\/h3>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/wp.unil.ch\/cavousestegal\/files\/2014\/10\/silhouette-74876_640.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-479 alignright\" src=\"https:\/\/wp.unil.ch\/cavousestegal\/files\/2014\/10\/silhouette-74876_640.png\" alt=\"silhouette-74876_640\" width=\"227\" height=\"165\" \/><\/a>Dans la perspective d&rsquo;une carri\u00e8re acad\u00e9mique, la mobilit\u00e9 est fortement valoris\u00e9e. Outre l&rsquo;enrichissement personnel qu&rsquo;offre cette exp\u00e9rience, elle constitue un atout d&rsquo;un point de vue professionnel. C&rsquo;est un excellent moyen de cr\u00e9er des contacts sur un plan international et d&rsquo;\u00e9largir ainsi son r\u00e9seau scientifique.<\/p>\n<p>Mais pour les chercheur-e-s vivant en couple ou en famille, l\u2019organisation d\u2019un s\u00e9jour de recherche \u00e0 l\u2019\u00e9tranger soul\u00e8ve des questions sp\u00e9cifiques et qui ne sont pas sans implications pour l\u2019\u00e9galit\u00e9 des chances.<\/p>\n<p>Comment faire coexister les projets professionnels des deux partenaires ? Quels soutiens existent dans les institutions pour r\u00e9pondre aux contraintes li\u00e9es \u00e0 la mobilit\u00e9 en famille ? Est-ce que les aides financi\u00e8res pour chercheur-e-s mobiles tiennent compte des besoins de couples et de familles ? Comment pr\u00e9parer le retour ?<\/p>\n<p>Le Bureau de l\u2019\u00e9galit\u00e9 a voulu soutenir les chercheur-e-s \u00e0 trouver des solutions \u00e0 ces questions. Depuis 2012, il offre \u00e0 la rel\u00e8ve un atelier intitul\u00e9 \u00a0\u00bb Mobilit\u00e9 en couple ou en famille\u00a0: quels enjeux, comment s\u2019y pr\u00e9parer ? \u00ab\u00a0.<\/p>\n<p>En 2014, l\u2019atelier a \u00e9t\u00e9 organis\u00e9 en collaboration avec le Dicast\u00e8re Rel\u00e8ve acad\u00e9mique et Diversit\u00e9 et a eu lieu le 6 juin dernier. Une vingtaine de chercheur-e-s, et une dizaine de conjoint-e-s, ont particip\u00e9 \u00e0 cet atelier qui a \u00e9t\u00e9 organis\u00e9 en deux parties. Dans un premier temps, des informations et t\u00e9moignages de chercheur-e-s mobiles ont permis de d\u00e9battre des questions soulev\u00e9es ci-dessus. La deuxi\u00e8me partie a \u00e9t\u00e9 consacr\u00e9e \u00e0 un conseil personnalis\u00e9.<\/p>\n<p>Au-del\u00e0 des ateliers propos\u00e9s, le BEC a particip\u00e9 \u00e0 la r\u00e9daction de la page \u00ab\u00a0Mobilit\u00e9\u00a0\u00bb du portail <a href=\"https:\/\/www.releve-academique.ch\">www.releve-academique.ch<\/a>. Dans cette page, les chercheur-e-s trouveront plusieurs conseils et ressources pour bien pr\u00e9parer leur s\u00e9jour scientifique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mobilit\u00e9 scientifique en couple ou en famille a des implications pour l\u2019\u00e9galit\u00e9 des chances. Les initiatives du Bureau de l\u2019\u00e9galit\u00e9 vise \u00e0 aider les chercheur-e-s \u00e0 mieux&hellip;<\/p>\n","protected":false},"author":1380,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[5,4,1],"tags":[],"class_list":{"0":"post-469","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-egalite","8":"category-parents","9":"category-tous-les-articles"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts\/469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/users\/1380"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/comments?post=469"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts\/469\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/media?parent=469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/categories?post=469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/tags?post=469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}