{"id":1803,"date":"2020-11-11T15:09:53","date_gmt":"2020-11-11T14:09:53","guid":{"rendered":"https:\/\/wp.unil.ch\/cavousestegal\/?p=1803"},"modified":"2023-03-13T17:00:46","modified_gmt":"2023-03-13T16:00:46","slug":"virgile-sottas-educateur-de-lenfance-a-la-garderie-le-polychinelle","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/cavousestegal\/2020\/11\/virgile-sottas-educateur-de-lenfance-a-la-garderie-le-polychinelle\/","title":{"rendered":"Virgile Sottas, \u00e9ducateur de l&rsquo;enfance \u00e0 la garderie le Polychinelle"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wp.unil.ch\/cavousestegal\/files\/2020\/11\/Capture-de\u0301cran-2020-11-11-a\u0300-13.17.01.png\" alt=\"\" class=\"wp-image-1790\" width=\"331\" height=\"325\" srcset=\"https:\/\/wp.unil.ch\/cavousestegal\/files\/2020\/11\/Capture-de\u0301cran-2020-11-11-a\u0300-13.17.01.png 592w, https:\/\/wp.unil.ch\/cavousestegal\/files\/2020\/11\/Capture-de\u0301cran-2020-11-11-a\u0300-13.17.01-300x294.png 300w, https:\/\/wp.unil.ch\/cavousestegal\/files\/2020\/11\/Capture-de\u0301cran-2020-11-11-a\u0300-13.17.01-80x80.png 80w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/><\/figure>\n\n\n\n<p><strong>Que faites-vous dans votre travail \u00e0 l\u2019UNIL&nbsp;?<\/strong><\/p>\n\n\n\n<p>Je suis \u00e9ducateur de l\u2019enfance et travaille dans l\u2019une des cr\u00e8ches du campus, au sein d\u2019une \u00e9quipe de neuf \u00e9ducatrices et \u00e9ducateurs. Notre mission est de prendre en charge des enfants, durant la journ\u00e9e, \u00e0 l\u2019ext\u00e9rieur de leur cercle familial. Nous veillons \u00e9galement \u00e0 ce que chaque enfant accueilli puisse grandir et s\u2019\u00e9panouir au sein d\u2019un groupe d\u2019enfants. Dans le groupe des \u00ab&nbsp;Moyens&nbsp;\u00bb, nous nous occupons d\u2019enfants \u00e2g\u00e9s de 2,5 \u00e0 4 ans.<\/p>\n\n\n\n<p>Notre travail est divis\u00e9 en deux parties&nbsp;: une partie sur le terrain, aupr\u00e8s des enfants et une autre partie (env. 10-15% de notre temps de travail) sans les enfants, pour tous les aspects administratifs.<\/p>\n\n\n\n<p>Durant la journ\u00e9e, nous accompagnons les enfants dans leurs jeux, les moments de repas ainsi que les moments de repos. Nous veillons \u00e0 ce que chaque enfant se sente bien tout au long de la journ\u00e9e.<\/p>\n\n\n\n<p><strong>En quelques mots, quel est votre parcours&nbsp;?<\/strong><\/p>\n\n\n\n<p>J\u2019ai effectu\u00e9 un apprentissage d\u2019\u00e9b\u00e9niste \u00e0 l\u2019ETML (Ecole des M\u00e9tiers de Lausanne). Lorsque j\u2019ai termin\u00e9, je me suis directement orient\u00e9 vers la profession d\u2019\u00e9ducateur de l\u2019enfance. J\u2019ai effectu\u00e9 des stages de longue dur\u00e9e \u00e0 l\u2019ESEDE (Ecole Sup\u00e9rieure en Education de l\u2019Enfance) \u00e0 Lausanne. Puis les choses se sont d\u00e9roul\u00e9es naturellement, en fonction des possibilit\u00e9s qui se sont offertes \u00e0 moi.<\/p>\n\n\n\n<p>Lorsque j\u2019\u00e9tais petit, je disais d\u00e9j\u00e0 que j\u2019aimais \u00ab&nbsp;m\u2019occuper des enfants&nbsp;\u00bb. Un int\u00e9r\u00eat qui s\u2019est r\u00e9v\u00e9l\u00e9 \u00e0 la naissance de ma s\u0153ur, lorsque j\u2019avais huit ans\u2026<\/p>\n\n\n\n<p><strong>Peu d\u2019hommes exercent cette fonction, quelle influence cela a-t-il eu et a encore sur votre carri\u00e8re&nbsp;?<\/strong><\/p>\n\n\n\n<p>Je ne saurais dire quelles influences, positives ou n\u00e9gatives, le fait d\u2019\u00eatre un homme a eues et a sur ma carri\u00e8re. En effet, bien qu\u2019\u00e9tant conscient des st\u00e9r\u00e9otypes de genre dans notre soci\u00e9t\u00e9, c\u2019est-\u00e0-dire du fait que les hommes et les femmes ont des pr\u00e9jug\u00e9s sp\u00e9cifiques li\u00e9s au genre, il m\u2019est difficile de distinguer ce qui est de l\u2019ordre des st\u00e9r\u00e9otypes de genre de ce qui est de l\u2019ordre de ma personnalit\u00e9 ainsi que de mes comp\u00e9tences.<\/p>\n\n\n\n<p>Il est possible que dans la recherche d\u2019un travail, \u00e0 comp\u00e9tences \u00e9gales, ma candidature soit favoris\u00e9e au profit d\u2019une candidature f\u00e9minine. Ceci dans le but de proposer une mixit\u00e9 de genre dans les \u00e9quipes \u00e9ducatives, et d\u2019avoir autant d\u2019hommes que de femmes qui travaillent en tant qu\u2019\u00e9ducateur\u00b7trice\u00b7s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que faites-vous dans votre travail \u00e0 l\u2019UNIL&nbsp;? Je suis \u00e9ducateur de l\u2019enfance et travaille dans l\u2019une des cr\u00e8ches du campus, au sein d\u2019une \u00e9quipe de neuf \u00e9ducatrices et&hellip;<\/p>\n","protected":false},"author":1001396,"featured_media":1790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[5,47,1],"tags":[],"class_list":{"0":"post-1803","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-egalite","8":"category-portraits","9":"category-tous-les-articles"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts\/1803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/users\/1001396"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/posts\/1803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/media\/1790"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/media?parent=1803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/categories?post=1803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/cavousestegal\/wp-json\/wp\/v2\/tags?post=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}