{"id":512,"date":"2025-05-21T09:50:42","date_gmt":"2025-05-21T07:50:42","guid":{"rendered":"https:\/\/wp.unil.ch\/ateliercomparatiste\/?p=512"},"modified":"2026-04-06T10:47:07","modified_gmt":"2026-04-06T08:47:07","slug":"glace-morte-ou-le-cri-dune-nature-en-sursis","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/ateliercomparatiste\/glace-morte-ou-le-cri-dune-nature-en-sursis\/","title":{"rendered":"<em>Glace morte<\/em> ou le cri d\u2019une nature en sursis"},"content":{"rendered":"\n<p>Dans son nouvel ouvrage <em>Glace morte<\/em>, Walter Rosselli peint avec po\u00e9sie une montagne meurtrie par l\u2019activit\u00e9 humaine et les d\u00e9r\u00e8glements climatiques qu\u2019elle a engendr\u00e9s. Entamant une derni\u00e8re marche, un fr\u00e8re et une s\u0153ur, le Nandou et la Schmied, souhaitent y attendre la mort, \u00e0 la mani\u00e8re des vieillards inuits. Le r\u00e9cit emm\u00e8ne ainsi le lecteur dans une r\u00e9flexion profonde sur l\u2019\u00e9cologie et le rapport de l\u2019homme \u00e0 la nature, tout en questionnant les imp\u00e9ratifs de la soci\u00e9t\u00e9 moderne.<\/p>\n\n\n\n<p>La prose vibrante rend toute la beaut\u00e9 de la montagne et de la for\u00eat qui se d\u00e9voilent au fil du p\u00e9riple et de ses \u00e9tapes. D\u00e9non\u00e7ant avec justesse l\u2019impact d\u2019une soci\u00e9t\u00e9 incapable d\u2019appr\u00e9cier la richesse du monde qui l\u2019accueille, le fr\u00e8re et la s\u0153ur regrettent de voir la nature immacul\u00e9e de leur enfance si maltrait\u00e9e aujourd\u2019hui.<\/p>\n\n\n\n<p>Chaque pas \u00ab&nbsp;d\u00e9clenchant une petite vague de souvenirs&nbsp;\u00bb (p. 116), le r\u00e9cit souligne \u00e9galement \u00e0 quel point la m\u00e9moire joue un r\u00f4le essentiel dans cet ultime voyage. Cette rem\u00e9moration des moments v\u00e9cus et les liens tiss\u00e9s accompagne les personnages et leur permet de faire le bilan d\u2019une vie bien remplie, dont ils semblent pourtant s\u2019\u00eatre d\u00e9tach\u00e9s.<\/p>\n\n\n\n<p>Cette marche, d\u2019abord pens\u00e9e comme un adieu au monde, se transforme finalement en un voyage \u00e0 la fois int\u00e9rieur et onirique. L\u2019\u00e9clat de la nature et les souvenirs persistants ravivent une lueur de d\u00e9sir. Dans cette clart\u00e9 nouvelle, une v\u00e9rit\u00e9 s\u2019impose&nbsp;: celle que la vie vaut tout de m\u00eame la peine d\u2019\u00eatre v\u00e9cue.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-l-039-atelier-comparatiste wp-block-embed-l-039-atelier-comparatiste\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"wZAkr32fKB\"><a href=\"https:\/\/wp.unil.ch\/ateliercomparatiste\/malika-vorlet\/\">Malika Vorlet<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Malika Vorlet\u00a0\u00bb &#8212; L&#039;Atelier comparatiste\" src=\"https:\/\/wp.unil.ch\/ateliercomparatiste\/malika-vorlet\/embed\/#?secret=53KBS2gp9f#?secret=wZAkr32fKB\" data-secret=\"wZAkr32fKB\" width=\"580\" height=\"327\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En racontant la derni\u00e8re marche d&rsquo;un fr\u00e8re et d&rsquo;une s\u0153ur, Walter Rosselli peint avec po\u00e9sie une montagne meurtrie par l\u2019activit\u00e9 humaine et les d\u00e9r\u00e8glements climatiques qu\u2019elle a engendr\u00e9s, en m\u00eame temps que le caract\u00e8re pr\u00e9cieux de la vie v\u00e9cue.<\/p>\n","protected":false},"author":1003000,"featured_media":515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[3,194],"tags":[19],"class_list":{"0":"post-512","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-critique","8":"category-critique-litteraire-2025","9":"tag-rosselli-walter"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/posts\/512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/users\/1003000"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/comments?post=512"}],"version-history":[{"count":4,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/posts\/512\/revisions"}],"predecessor-version":[{"id":558,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/posts\/512\/revisions\/558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/media\/515"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/media?parent=512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/categories?post=512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/ateliercomparatiste\/wp-json\/wp\/v2\/tags?post=512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}