{"id":9376,"date":"2019-01-31T08:25:19","date_gmt":"2019-01-31T06:25:19","guid":{"rendered":"http:\/\/wp.unil.ch\/allezsavoir\/?p=9376"},"modified":"2020-07-22T14:32:58","modified_gmt":"2020-07-22T12:32:58","slug":"etrangers-dans-les-prisons-suisses-pourquoi-ils-sont-si-nombreux","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/allezsavoir\/etrangers-dans-les-prisons-suisses-pourquoi-ils-sont-si-nombreux\/","title":{"rendered":"Etrangers dans les prisons suisses, pourquoi ils sont si nombreux"},"content":{"rendered":"<figure id=\"attachment_9520\" aria-describedby=\"caption-attachment-9520\" style=\"width: 590px\" class=\"wp-caption alignnone\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-9520 size-full\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/prison_1_72.jpg\" alt=\"\" width=\"590\" height=\"393\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/prison_1_72.jpg 590w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/prison_1_72-390x260.jpg 390w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><figcaption id=\"caption-attachment-9520\" class=\"wp-caption-text\">En Suisse, en 2017, 8071 personnes sont entr\u00e9es en prison. Parmi elles, 5299 \u00e9trangers. Ici, une vue de l\u2019\u00e9tablissement d\u2019ex\u00e9cution des peines de Bellevue (Gorgier, Neuch\u00e2tel).<br \/>\u00a9 Valentin Flauraud \/ Keystone<\/figcaption><\/figure>\n<p><em>Avec une population carc\u00e9rale compos\u00e9e \u00e0 71,5% d\u2019\u00e9trangers, la Suisse est proche du record europ\u00e9en. Pourquoi nos prisons comptent-elles autant de ressortissants venus d\u2019ailleurs et comment y rem\u00e9dier? Explications et pistes avec trois sp\u00e9cialistes.<\/em><\/p>\n<p>\u00abAlors que la Suisse compte un quart d\u2019\u00e9trangers dans sa population, pr\u00e8s des trois-quarts des d\u00e9linquants incarc\u00e9r\u00e9s sont \u00e9trangers. On a un probl\u00e8me. Ou \u00e0 tout le moins une surrepr\u00e9sentation\u00bb, corrige Marcelo Aebi, vice-directeur de l\u2019\u00c9cole des sciences criminelles de l\u2019Universit\u00e9 de Lausanne. Avocat et criminologue de formation, il s\u2019occupe des Statistiques p\u00e9nales annuelles du Conseil de l\u2019Europe (projet SPACE) depuis 2002. Les prisons, leurs d\u00e9tenus et les chiffres, il conna\u00eet. Alors, lorsqu\u2019il s\u2019agit de commenter le pourcentage d\u2019\u00e9trangers dans les prisons suisses, soit 71,5% (chiffre de 2017), il appelle un chat un chat. Ce professeur, qui a grandi en Argentine, d\u00e9plore le fait que beaucoup de gens commentent ces chiffres d\u2019un point de vue politique: \u00abSi la personne est de droite, elle dit: \u201c Regardez tous ces \u00e9trangers en prison!\u201d Si elle est de gauche, elle pr\u00e9tend qu\u2019il n\u2019y a rien de sp\u00e9cial \u00e0 dire. Il faut sortir de ce cadre-l\u00e0 et essayer d\u2019analyser les choses d\u2019un point de vue scientifique.\u00bb<\/p>\n<p><strong>La Suisse presque championne<\/strong><br \/>\nEn comparaison europ\u00e9enne, avec une population carc\u00e9rale compos\u00e9e \u00e0 71,5% d\u2019\u00e9trangers, la Suisse occupe la premi\u00e8re place des pays comptant plus de 1 million d\u2019habitants. Monaco, Andorre et le Luxembourg comptabilisent bien une part sup\u00e9rieure, mais la comparaison est difficile, vu leur tr\u00e8s faible population. Ces trois pays r\u00e9unis comptent en effet moins de 700000 habitants. A l\u2019autre extr\u00e9mit\u00e9, la Pologne compte 0,9% d\u2019\u00e9trangers en prison. Dans les 47 \u00c9tats membres du Conseil de l\u2019Europe pris ensemble et participant \u00e0 l\u2019enqu\u00eate annuelle, la part est de 21,2%.<\/p>\n<p>Mais revenons \u00e0 la Suisse et \u00e0 sa place sur la premi\u00e8re marche du podium. Cette proportion est relativement stable depuis plus de dix ans, m\u00eame si elle n\u2019est pas \u00e9gale dans toutes les r\u00e9gions du pays: elle est de 65% en Suisse orientale, de 68% en Suisse centrale et du nord-est et se monte \u00e0 79% dans les cantons latins. De fait, cette diff\u00e9rence refl\u00e8te le \u00abR\u00f6stigraben\u00bb entre la conception al\u00e9manique et romande de la politique criminelle.<\/p>\n<p>Charg\u00e9 de cours \u00e0 l\u2019Universit\u00e9 de Lausanne et de Lucerne o\u00f9 il enseigne la statistique criminelle et auteur d\u2019un ouvrage sur les prisons suisses (1), Daniel Fink confirme que les Romands font un usage particuli\u00e8rement fr\u00e9quent de la privation de libert\u00e9.<\/p>\n<p>Pour ce qui est de l\u2019\u00e9galit\u00e9 de traitement entre ressortissants suisses et \u00e9trangers, elle est respect\u00e9e, affirme Marcelo Aebi. \u00abLes \u00e9tudes sont claires: les \u00e9trangers ne sont pas condamn\u00e9s \u00e0 des peines plus lourdes. Le juge applique le code, ind\u00e9pendamment de qui est la personne.\u00bb<\/p>\n<figure id=\"attachment_9466\" aria-describedby=\"caption-attachment-9466\" style=\"width: 262px\" class=\"wp-caption alignnone\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-9466 size-full\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/DanielFink_72.jpg\" alt=\"\" width=\"262\" height=\"393\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/DanielFink_72.jpg 262w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/DanielFink_72-173x260.jpg 173w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><figcaption id=\"caption-attachment-9466\" class=\"wp-caption-text\">Daniel Fink. Charg\u00e9 de cours \u00e0 l\u2019UNIL.<br \/>Nicole Chuard \u00a9 UNIL<\/figcaption><\/figure>\n<p><strong>Romands r\u00e9pressifs<\/strong><br \/>\nN\u2019emp\u00eache, si le code est le m\u00eame pour tous, la palme d\u2019or en mati\u00e8re de ch\u00e2timent toutes nationalit\u00e9s confondues revient aux cantons de Vaud et Gen\u00e8ve. \u00abAlors que ces deux cantons repr\u00e9sentent 14,6% de la population suisse, ils prononcent 43,4% de toutes les peines.\u00bb Cherchez l\u2019erreur. Une explication? \u00abC\u2019est Pierre Maudet, le conseiller d\u2019\u00c9tat, et Olivier Jornot, le procureur g\u00e9n\u00e9ral, des <em>hardliners<\/em> en mati\u00e8re de condamnation. Il y a tout un climat, en tout cas \u00e0 Gen\u00e8ve comparativement \u00e0 Zurich ou \u00e0 B\u00e2le\u00bb, indique Daniel Fink.<\/p>\n<p>Et cet ancien chef de la section Criminalit\u00e9 et droit p\u00e9nal de l\u2019Office f\u00e9d\u00e9ral de la statistique (OFS) d\u2019\u00e9voquer encore la part tr\u00e8s \u00e9lev\u00e9e des \u00e9trangers non-r\u00e9sidents \u00e0 Champ-Dollon, atteignant par moments jusqu\u2019\u00e0 80%, tout au moins en d\u00e9tention avant jugement. \u00abEn Suisse, un quart de toutes les d\u00e9tentions provisoires sont r\u00e9alis\u00e9es \u00e0 Gen\u00e8ve. Et qui va en d\u00e9tention provisoire? Ce sont les \u00e9trangers non domicili\u00e9s en Suisse. Il y en a pourtant certainement autant \u00e0 B\u00e2le et \u00e0 Zurich.\u00bb De fait, \u00e0 la prison de Champ-Dollon, le pourcentage d\u2019\u00e9trangers s\u2019\u00e9l\u00e8ve \u00e0 89% et dans tout le canton de Gen\u00e8ve il est de 86% (chiffres 2017).<\/p>\n<p>Lorsque l\u2019on \u00e9voque le nombre de d\u00e9tenus \u00e9trangers, il est important de commencer par distinguer deux cat\u00e9gories diff\u00e9rentes, rappelle Marcelo Aebi: ceux qui r\u00e9sident en Suisse et ceux qui n\u2019y sont pas \u00e9tablis. Parmi ces derniers, certains entrent en Suisse uniquement pour commettre un d\u00e9lit. On appelle \u00e7a le tourisme criminel ou la criminalit\u00e9 transfrontali\u00e8re. La saison la plus propice pour ce genre de d\u00e9lits de cambriolage \u00e9tant les mois d\u2019octobre \u00e0 f\u00e9vrier, lorsque le jour tombe rapidement et que la lumi\u00e8re trahit la pr\u00e9sence ou non des futures victimes. La police parle de bandes internationales organis\u00e9es dont beaucoup viennent des pays de l\u2019Est. Situ\u00e9 au c\u0153ur de l\u2019Europe, la Suisse, territoire de transit, est une cible toute d\u00e9sign\u00e9e pour toutes sortes de malfrats qui viennent y commettre des d\u00e9lits, richesse du pays oblige. Beaucoup de pavillons et de villas ressemblent \u00e0 de v\u00e9ritables cavernes d\u2019Ali Baba. De m\u00eame, la prosp\u00e9rit\u00e9 de la Suisse attire les \u00e9migr\u00e9s qui souhaitent se construire un avenir meilleur, en trouvant du travail.<\/p>\n<p>Charg\u00e9e de cours \u00e0 l\u2019\u00c9cole des sciences criminelles, Natalia Delgrande, qui a travaill\u00e9 durant dix ans au projet SPACE au c\u00f4t\u00e9 de Marcelo Aebi, temp\u00e8re l\u2019expression de tourisme criminel. \u00abGlobalisation oblige, nous sommes tous en mouvement, m\u00eame les criminels. On ne dit pas non plus des \u00e9tudiants qui viennent en Erasmus qu\u2019ils font du tourisme universitaire. On parle partout des bandes de \u201ctouristes g\u00e9orgiens\u201d, mais en prison ils repr\u00e9sentent 0,7% de tous les \u00e9trangers. Le crime est une constante, y compris dans la nouvelle r\u00e9alit\u00e9 de la globalisation.\u00bb Voil\u00e0 qui est dit. Qui sont-ils? \u00abQuand on veut analyser la composition de cette cat\u00e9gorie d\u2019\u00e9trangers, on constate qu\u2019aucune ethnie n\u2019arrive \u00e0 10%. On peut m\u00eame prendre toute l\u2019Europe de l\u2019Est, on n\u2019a pas de profil majoritaire.\u00bb<\/p>\n<p><strong>Univers masculin<\/strong><br \/>\nSi l\u2019OFS ne tient pas de statistique sur ces touristes d\u2019un genre particulier dont certains finissent derri\u00e8re les barreaux, elle comptabilise en revanche les \u00e9trangers (\u00e8res) sans livret B ou C selon la nationalit\u00e9. En 2016, l\u2019effectif (nombre de d\u00e9tenus au jour du relev\u00e9) \u00e9tait de 2580, avec, sur les trois premi\u00e8res marches du podium, les ressortissants de l\u2019Afrique du Nord (486), ceux de l\u2019Ouest (441) et des citoyens de l\u2019ancienne R\u00e9publique f\u00e9d\u00e9rale de Yougoslavie (370). Les viennent-ensuite sont les Albanais (234), les Roumains (200) et les Fran\u00e7ais (96).<\/p>\n<p>Toutes nationalit\u00e9s confondues, les femmes ne repr\u00e9sentent que 5,6% (2017) de la population carc\u00e9rale. Si elles sont parvenues \u00e0 l\u2019\u00e9galit\u00e9 en ce qui concerne les d\u00e9lits \u00e0 la propri\u00e9t\u00e9, elles commettent moins de d\u00e9lits graves et violents et sont moins impliqu\u00e9es dans le trafic de drogue.<\/p>\n<p>Autre statistique de l\u2019OFS: celle des condamnations. En 2017, 39899 Suisses, 23898 \u00e9trangers r\u00e9sidents en Suisse (sans asile) et 32374 \u00abautres \u00e9trangers\u00bb ont \u00e9t\u00e9 condamn\u00e9s. Tous ne finissent bien s\u00fbr pas en prison. Les apparences seraient-elles trompeuses? Comment faut-il analyser tous ces chiffres en \u00e9vitant de mettre des lunettes aux verres teint\u00e9s d\u2019ang\u00e9lisme? Marcelo Aebi pr\u00e9f\u00e8re sortir des arguments chiffr\u00e9s de sa besace, l\u2019\u00e9cran de son ordinateur en l\u2019occurrence, pour argumenter. \u00abEn Suisse, nous avons un pourcentage tr\u00e8s \u00e9lev\u00e9 d\u2019\u00e9trangers \u00e9tablis de mani\u00e8re l\u00e9gale. Il s\u2019\u00e9l\u00e8ve \u00e0 25% au niveau national. Dans les grandes villes, ce taux est sup\u00e9rieur, comme \u00e0 Lausanne par exemple o\u00f9 il atteint 43%.\u00bb En Europe, seul le Luxembourg compte un taux plus \u00e9lev\u00e9 (45,3%). Pour les autres pays, on compte une proportion sup\u00e9rieure \u00e0 10% \u00e0 Chypre (19,5%), en Lettonie (15,2%), en Estonie (14,9%), en Autriche (12,5%), en Irlande (11,8%), en Belgique (11,3%) et en Espagne (10,1%).<\/p>\n<figure id=\"attachment_9507\" aria-describedby=\"caption-attachment-9507\" style=\"width: 262px\" class=\"wp-caption alignnone\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-9507 size-full\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/MarceloAebi_72.jpg\" alt=\"\" width=\"262\" height=\"393\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/MarceloAebi_72.jpg 262w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/MarceloAebi_72-173x260.jpg 173w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><figcaption id=\"caption-attachment-9507\" class=\"wp-caption-text\">Marcelo Aebi. Professeur, vice-directeur de l\u2019\u00c9cole des sciences criminelles (Facult\u00e9 de droit, des sciences criminelles et d\u2019administration publique).<br \/>Nicole Chuard \u00a9 UNIL<\/figcaption><\/figure>\n<p><strong>D\u00e9linquance et forme physique<\/strong><br \/>\nOn est cependant loin du compte pour expliquer cette proportion de 71,5% de prisonniers \u00e9trangers qui fait sourciller plus d\u2019un citoyen suisse. A l\u2019instar de Marcelo Aebi, Daniel Fink affirme qu\u2019il faut tenir compte de la composition de la population \u00e9trang\u00e8re et non pas seulement de la cat\u00e9gorie \u00ab\u00e9tranger\u00bb. \u00abLes Suisses sont en moyenne plus \u00e2g\u00e9s que la population \u00e9trang\u00e8re r\u00e9sidente. Les requ\u00e9rants, les migrants et les ill\u00e9gaux sont plut\u00f4t des hommes jeunes.\u00bb Et alors? \u00abLa criminalit\u00e9 est un ph\u00e9nom\u00e8ne de jeunes: 35 ans en moyenne pour les d\u00e9tenus, mais 21 ans pour le pic de la criminalit\u00e9. Apr\u00e8s, le nombre de personnes commettant des infractions baisse continuellement.\u00bb De fait, comme pour les sportifs, la d\u00e9linquance \u2013 qui est une activit\u00e9 physique, surtout lorsqu\u2019elle implique de la violence \u2013 demande de la r\u00e9sistance, une r\u00e9sistance qui n\u2019est pas la m\u00eame \u00e0 20 ans qu\u2019\u00e0 50 ans. \u00abOn devrait en g\u00e9n\u00e9ral comparer les hommes selon les classes d\u2019\u00e2ge, c\u2019est-\u00e0-dire comparer ce qui peut l\u2019\u00eatre. Il faut \u00e9galement comparer les \u00e9trangers qui sont en prison et qui habitent sur le sol helv\u00e9tique avec les \u00e9trangers qui vivent en Suisse.\u00bb<\/p>\n<p><strong>In\u00e9galit\u00e9 sociale<\/strong><br \/>\nSi la structure d\u2019\u00e2ge explique partiellement la diff\u00e9rence de la proportion de Suisses et d\u2019\u00e9trangers incarc\u00e9r\u00e9s, Daniel Fink pointe \u00e9galement du doigt la structure sociale. \u00abElle est en d\u00e9faveur des \u00e9trangers, c\u2019est \u00e9vident. Ils sont moins fortun\u00e9s que les Suisses, ont moins d\u2019emplois stables, moins de perspectives professionnelles et sont licenci\u00e9s plus rapidement. Ils auront moins la chance d\u2019avoir un avocat qui va les sortir des ennuis et pourront moins faire valoir leurs droits, en tout cas ceux qui sont en d\u00e9crochage et qui ne voient pas leur futur au-del\u00e0 de leur situation actuelle.\u00bb<\/p>\n<p>D\u2019autres sont traumatis\u00e9s par la guerre, n\u2019arrivent pas \u00e0 s\u2019int\u00e9grer ou r\u00e9solvent leurs probl\u00e8mes en faisant justice eux-m\u00eames, ne cherchant pas le dialogue, faute de connaissances linguistiques suffisantes. Les circonstances att\u00e9nuantes sont ind\u00e9niables, mais peut-il tout de m\u00eame concevoir que les chiffres choquent? \u00abOui, mais \u00e7a montre quand m\u00eame que l\u2019on ne peut pas lire les chiffres tels quels. Que ce soit les Afghans, les Somali, les \u00c9rythr\u00e9ens, il faudrait tout de m\u00eame voir d\u2019o\u00f9 viennent ces migrants, comment on les accueille et quelle est leur situation.\u00bb<\/p>\n<figure id=\"attachment_9512\" aria-describedby=\"caption-attachment-9512\" style=\"width: 262px\" class=\"wp-caption alignnone\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-9512 size-full\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/NataliaDelgrande_72.jpg\" alt=\"\" width=\"262\" height=\"393\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/NataliaDelgrande_72.jpg 262w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2019\/01\/NataliaDelgrande_72-173x260.jpg 173w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><figcaption id=\"caption-attachment-9512\" class=\"wp-caption-text\">Natalia Delgrande. Charg\u00e9e de cours \u00e0 l\u2019\u00c9cole des sciences criminelles (Facult\u00e9 de droit, des sciences criminelles et d\u2019administration publique).<br \/>Nicole Chuard \u00a9 UNIL<\/figcaption><\/figure>\n<p><strong>Jeunes Allemands, bons \u00e9l\u00e8ves<\/strong><br \/>\nCet ex-d\u00e9l\u00e9gu\u00e9 du CICR d\u00e9plore \u00abl\u2019esp\u00e8ce de logique de la responsabilit\u00e9 individuelle\u00bb qui pr\u00e9vaut actuellement, alors que, auparavant, la soci\u00e9t\u00e9 prenait en compte les causes sociales qui menaient au crime. \u00abLa criminalit\u00e9 est \u00e9galement li\u00e9e \u00e0 des in\u00e9galit\u00e9s sociales et des perspectives de futur in\u00e9gales selon les classes sociales. La d\u00e9linquance, on n\u2019y tombe pas dedans parce qu\u2019on a du plaisir \u00e0 \u00eatre dedans, ou parce qu\u2019on a choisi.\u00bb Pour \u00e9tayer ses propos, Daniel Fink cite l\u2019exemple des Allemands, soit les 18 \u00e0 29 ans, la tranche d\u2019\u00e2ge la plus \u00e0 risque question d\u00e9linquance. Constat: leur taux de criminalit\u00e9 est moindre que celui des Suisses. Pourquoi donc? \u00abParce que les 18-29 ans qui viennent d\u2019Allemagne ont majoritairement des dipl\u00f4mes sup\u00e9rieurs et ont tous un travail, donc leur taux de criminalit\u00e9 est moindre par rapport aux Suisses. C\u2019est donc bien la preuve que la structure sociale du groupe de r\u00e9f\u00e9rence doit \u00eatre prise en compte.\u00bb<\/p>\n<p>On l\u2019aura compris, derri\u00e8re les chiffres se cachent souvent une r\u00e9alit\u00e9 plus complexe. Natalia Delgrande constate que la Suisse se montre particuli\u00e8rement tatillonne lorsqu\u2019il s\u2019agit d\u2019accorder le passeport \u00e0 croix blanche. \u00abEn Suisse, dans les statistiques carc\u00e9rales, on inclut parmi les \u00e9trangers les personnes poss\u00e9dant un permis d\u2019\u00e9tablissement de longue dur\u00e9e, le permis B ou C.\u00bb La proportion des personnes qui poss\u00e8dent ce genre de livret s\u2019\u00e9l\u00e8ve \u00e0 environ 20% du total des d\u00e9tenus. La jeune femme souligne la complexit\u00e9 de la proc\u00e9dure d\u2019acquisition de la nationalit\u00e9 suisse. \u00abLa vitesse d\u2019assimilation du solde migratoire est tr\u00e8s lente. Nos voisins, eux, ne connaissent pas le concept de 3e g\u00e9n\u00e9ration d\u2019\u00e9trangers, alors que nous, nous avons beaucoup d\u2019\u00e9trangers de la 2e et 3e g\u00e9n\u00e9ration.\u00bb<\/p>\n<p>Responsable de projets et d\u00e9veloppement au Centre suisse de comp\u00e9tences en mati\u00e8re d\u2019ex\u00e9cution des sanctions p\u00e9nales, la charg\u00e9e de cours conna\u00eet bien le monde carc\u00e9ral. Elle remarque \u00e9galement, que contrairement \u00e0 d\u2019autres pays europ\u00e9ens, la Suisse n\u2019applique pas les d\u00e9cisions cadres de l\u2019UE qui permettent de renvoyer les personnes incarc\u00e9r\u00e9es dans leur pays pour purger leur peine. \u00abIl existe m\u00eame la possibilit\u00e9 d\u2019\u00eatre expuls\u00e9 dans un pays europ\u00e9en dans lequel la personne a des liens sociaux, par exemple une partie de sa famille, un coin de terre. La chance est ainsi plus grande de ne pas retomber dans la criminalit\u00e9&#8230;\u00bb<\/p>\n<p>Criminalit\u00e9 transfrontali\u00e8re, forte proportion d\u2019\u00e9trangers dans la population, in\u00e9galit\u00e9 des chances, lenteur pour l\u2019obtention du passeport suisse, faillite dans l\u2019int\u00e9gration d\u2019une population jeune et masculine, donc plus susceptible de commettre des d\u00e9lits, voici des facteurs qui peuvent expliquer le taux \u00e9lev\u00e9 d\u2019\u00e9trangers dans les prisons suisses.<\/p>\n<p>Les solutions? Pour ce qui est de la criminalit\u00e9 itin\u00e9rante, Marcelo Aebi n\u2019en voit aucune. Intensifier les contr\u00f4les aux fronti\u00e8res provoquerait des embouteillages sur des dizaines de kilom\u00e8tres. Pour ce qui est de la criminalit\u00e9 des \u00e9trangers r\u00e9sidents en revanche, il a des solutions. \u00abCela passe par des cours d\u2019int\u00e9gration, mais \u00e9galement de langue. Si l\u2019on n\u2019arrive pas \u00e0 se faire comprendre, on peut devenir violent. Cela dit, en Suisse, l\u2019int\u00e9gration des \u00e9trangers se passe bien.\u00bb \u00c9videmment, on peut toujours faire mieux. A l\u2019\u00e9cole, l\u2019int\u00e9gration devrait commencer tr\u00e8s t\u00f4t et de fa\u00e7on radicale. \u00abAu Danemark par exemple, les Autorit\u00e9s distribuent les \u00e9l\u00e8ves \u00e9trangers de mani\u00e8re \u00e9quitable dans la population.\u00bb Quelle serait concr\u00e8tement la marche \u00e0 suivre pour le canton de Vaud, par exemple? \u00abIl faudrait d\u00e9placer une partie des \u00e9l\u00e8ves du Gros-de-Vaud, o\u00f9 il n\u2019y a pas d\u2019\u00e9trangers, dans les \u00e9coles du centre de Lausanne, o\u00f9 il y a 50% d\u2019\u00e9l\u00e8ves \u00e9trangers. Evidemment, \u00e7a implique un investissement, mais c\u2019est un choix. Il faut juste \u00eatre s\u00fbr de ce que l\u2019on veut.\u00bb<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8290\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2017\/09\/livre_prison_fink_67.jpg\" alt=\"\" width=\"100\" height=\"150\" \/><\/p>\n<p>(1) <em>La prison en Suisse, un \u00e9tat des lieux<\/em>. Par Daniel Fink. Presses polytechniques et universitaires romandes (2017), 135 p. Traduit en allemand sous le titre <em>Freiheitsentzug in der Schweiz, Formen, Effizienz, Bedeutung<\/em>. Ed. NZZ Libro (2018), 183 p.<\/p>\n<h3>Univers carc\u00e9ral et criminalit\u00e9 en chiffres<\/h3>\n<p>\u2022 Nombre d\u2019\u00e9tablissements de privation de libert\u00e9 en 2017: 106<br \/>\n\u2022 Taux d\u2019occupation: 92,5%<br \/>\n\u2022 Adultes incarc\u00e9r\u00e9s (effectif*): 6863<br \/>\n\u2022 Pourcentage de femmes: 5,6%<br \/>\n\u2022 Pourcentage d\u2019\u00e9trangers: 71,5%<br \/>\n\u2022 Plus grande prison de Suisse:<br \/>\nP\u00f6schwies \u00e0 Regensdorf (ZH), 460 places<\/p>\n<p>Sur les 6863 d\u00e9tenus, 1673 personnes font l\u2019objet de mesures de contrainte selon la loi sur les \u00e9trangers (en vue d\u2019un renvoi ou expulsion)<\/p>\n<p><strong>Nombre de personnes condamn\u00e9es<\/strong><br \/>\n\u2022 Suisses: 39899<br \/>\n\u2022 \u00c9trangers r\u00e9sidents en Suisse<br \/>\n(sans asile): 23898<br \/>\n\u2022 Autres \u00e9trangers: 32374<br \/>\nNombre d\u2019incarc\u00e9rations (2017)<br \/>\n\u2022 Suisses: 2772<br \/>\n\u2022 \u00c9trangers: 5299<br \/>\n\u2022 Total: 8071<\/p>\n<p><strong>Nombre d\u2019incarc\u00e9rations selon\u00a0la nationalit\u00e9 (10 premiers rangs, 2017)<\/strong><br \/>\n\u2022 Suisse: 2772<br \/>\n\u2022 Afrique du Nord: 868<br \/>\n\u2022 Ancienne r\u00e9publique f\u00e9d\u00e9rale<br \/>\nde Yougoslavie: 735<br \/>\n\u2022 Afrique de l\u2019Ouest: 671<br \/>\n\u2022 Roumanie: 394<br \/>\n\u2022 Portugal: 242<br \/>\n\u2022 France: 226<br \/>\n\u2022 Italie: 221<br \/>\n\u2022 Allemagne: 198<br \/>\n\u2022 \u00c9rythr\u00e9e: 167<\/p>\n<p><strong>Taux d\u2019incarc\u00e9ration (incidence par ann\u00e9e et par 1000 habitants de la Suisse)<\/strong><br \/>\n\u2022 Suisse: 0,44<br \/>\n\u2022 Afrique du Nord: 2,88<br \/>\n\u2022 Ancienne r\u00e9publique f\u00e9d\u00e9rale de Yougoslavie: 0,98<br \/>\n\u2022 Afrique de l\u2019Ouest: 4,67<br \/>\n\u2022 Roumanie: 0,48<br \/>\n\u2022 Portugal: 0,63<br \/>\n\u2022 France: 0,38<br \/>\n\u2022 Italie: 0,47<br \/>\n\u2022 Allemagne: 0,32<br \/>\n\u2022 \u00c9rythr\u00e9e: 1,66<\/p>\n<p>* Effectif: nombre de d\u00e9tenus au jour du relev\u00e9<br \/>\nIncarc\u00e9rations: nombre de d\u00e9tenus entrant en prison sur une ann\u00e9e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec une population carc\u00e9rale compos\u00e9e \u00e0 71,5% d\u2019\u00e9trangers, la Suisse est proche du record europ\u00e9en. Pourquoi nos prisons comptent-elles autant de ressortissants venus d\u2019ailleurs et comment y rem\u00e9dier? Explications et &hellip; <\/p>\n","protected":false},"author":825,"featured_media":9521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[42178,42172,35],"tags":[42166],"class_list":{"0":"post-9376","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-no-71","8":"category-sciences-criminelles","9":"category-societe","10":"tag-sabine-pirolt"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/9376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/users\/825"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/comments?post=9376"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/9376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media\/9521"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media?parent=9376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/categories?post=9376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/tags?post=9376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}