{"id":4657,"date":"2013-05-23T08:14:06","date_gmt":"2013-05-23T06:14:06","guid":{"rendered":"http:\/\/wp.unil.ch\/allezsavoir\/?p=4657"},"modified":"2020-07-29T14:41:46","modified_gmt":"2020-07-29T12:41:46","slug":"le-titanic-vogue-encore-dans-notre-imagination","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/allezsavoir\/le-titanic-vogue-encore-dans-notre-imagination\/","title":{"rendered":"Le \u00ab\u00a0Titanic\u00a0\u00bb vogue encore&#8230; dans notre imagination"},"content":{"rendered":"<p><em><a href=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2013\/01\/as10_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4285\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2013\/01\/as10_cover.jpg\" alt=\"as10_cover\" width=\"100\" height=\"138\" \/><\/a><\/em><\/p>\n<p><em>L\u2019\u00e9dition 2013 des Myst\u00e8res de l\u2019UNIL a pris le c\u00e9l\u00e8bre paquebot comme m\u00e9taphore d\u2019une soci\u00e9t\u00e9 utopique naviguant sur des eaux dangereuses. Un mythe qui perdure: Allez savoir! avait trait\u00e9 de notre fascination pour le \u00abTitanic\u00bb il y a quinze ans.<\/em><\/p>\n<p>\u00abMais qu\u2019est-ce qui nous attire \u00e0 ce point dans ce d\u00e9sastre? Qu\u2019est-ce qui nous captive dans ce drame maritime au point que, huitante-six ans plus tard, \u201cil continue de hanter notre imaginaire\u201d?\u00bb, \u00e9crivait Patricia Brambilla dans l\u2019\u00e9dition de janvier 1998<br \/>\nd\u2019Allez savoir!<\/p>\n<p>La journaliste avait interrog\u00e9 Jean-Pierre Keller, alors professeur \u00e0 la Facult\u00e9 des sciences sociales et politiques et auteur de Sur le pont du Titanic*. Aujourd\u2019hui professeur honoraire, l\u2019enseignant indiquait que la trajectoire du paquebot \u00ab[&#8230;] contient tous les \u00e9l\u00e9ments du mythe et est embl\u00e9matique \u00e0 plusieurs points de vue\u00bb. A commencer par le fait qu\u2019il s\u2019agit de l\u2019histoire d\u2019un bateau. Et non d\u2019un avion ou d\u2019un train. D\u00e9tail insignifiant? Pas pour le sociologue qui fait remarquer que l\u2019homme entretient une relation diff\u00e9rente avec un navire qu\u2019avec tout autre moyen de locomotion: \u00abOn personnifie les bateaux en leur donnant un nom. On dit le Queen Elisabeth, le France&#8230; Et puis en anglais, les bateaux ne sont pas neutres, ils sont f\u00e9minins. On dit \u201cshe\u201d. Une habitude qui doit sans doute remonter tr\u00e8s loin, \u00e0 l\u2019\u00e9poque des marins qui prenaient la mer. Autant de signes qui donnent au bateau une place \u00e0 part dans notre imaginaire.\u00bb<\/p>\n<p>\u00abEnsuite, le Titanic, ce n\u2019est pas n\u2019importe quel rafiot. On parle du \u201cplus grand objet mobile jamais r\u00e9alis\u00e9 par l\u2019homme\u201d. Mieux, il incarnait le luxe et la modernit\u00e9, il \u00e9tait le sommet de la r\u00e9alisation technique, la fiert\u00e9 d\u2019une \u00e9poque arrogante, enivr\u00e9e de son propre progr\u00e8s. Imaginez une embarcation de 270 m\u00e8tres de long et de 31 m\u00e8tres de haut, forte de quatre chemin\u00e9es (dont une postiche, install\u00e9e uniquement pour l\u2019esth\u00e9tique et l\u2019effet de grandeur) [&#8230;].\u00bb<\/p>\n<p>\u00abCette v\u00e9ritable ville flottante qui pouvait contenir jusqu\u2019\u00e0 2?500 passagers \u00e9tait consid\u00e9r\u00e9e comme insubmersible. Le fait qu\u2019elle ait sombr\u00e9 a vraiment frapp\u00e9 les esprits: \u201cC\u2019est comme si la modernit\u00e9 elle-m\u00eame coulait. Aujourd\u2019hui, on est habitu\u00e9 \u00e0 douter de la technique, gr\u00e2ce en partie au discours \u00e9cologique. Mais \u00e0 la Belle Epoque, tout ce qui \u00e9tait moderne \u00e9tait bien. Le naufrage du Titanic a vraiment marqu\u00e9 la fin d\u2019une \u00e9poque\u201d, souligne Jean-Pierre Keller. On y a vu une parabole, une le\u00e7on d\u2019humilit\u00e9, un ch\u00e2timent \u00e0 l\u2019orgueil des hommes. Qui, dans leur course prom\u00e9th\u00e9enne, avaient oubli\u00e9 une fois de plus que la nature \u00e9tait la plus forte. Qu\u2019elle \u00e9tait indomptable et qu\u2019elle pouvait \u00eatre cruelle.\u00bb<\/p>\n<p>\u00abEt puis, le Titanic \u00e9tait bond\u00e9 de passagers aux destins passionnants: tout le gratin britannique \u00e9tait l\u00e0, de l\u2019armateur du bateau au pr\u00e9sident de la compagnie White Star Line. Sans parler de quelques richissimes personnalit\u00e9s am\u00e9ricaines: le couple Straus, propri\u00e9taire du magasin Macy\u2019s \u00e0 New York, ou Benjamin Guggenheim, fils du nabab Meyer Guggenheim. Sur le bateau se trouvait aussi une large frange d\u2019immigrants, pour la plupart partis d\u2019Orient avec tous leurs bagages, pr\u00eats \u00e0 recommencer leur vie sur le nouveau continent. Mais, d\u2019apr\u00e8s le sociologue, c\u2019est la pr\u00e9sence de quelques richissimes personnalit\u00e9s qui constitue l\u2019\u00e9l\u00e9ment marquant du sc\u00e9nario: \u201cLa richesse nous fascine. On n\u2019y peut rien. M\u00eame les gens qui votent \u00e0 gauche sont davantage int\u00e9ress\u00e9s par la mort des riches&#8230;. On l\u2019a vu avec Lady Di\u201d.\u00bb<\/p>\n<p>Dans sa conclusion, Patricia Brambilla rappelait que le nom m\u00eame du navire \u00e9tait \u00abune allusion directe \u00e0 la mythologie grecque. Les Titans ne sont-ils pas les enfants d\u2019Ouranos, qui s\u2019\u00e9taient r\u00e9volt\u00e9s contre Zeus, le dieu de l\u2019Olympe, puis avaient \u00e9t\u00e9 vaincus et jet\u00e9s dans l\u2019ab\u00eeme du Tartare? Le Titanic \u00e9tait entr\u00e9 dans la mythologie de son vivant, son naufrage l\u2019y a d\u00e9finitivement assign\u00e9. Puisqu\u2019il continuera sans doute encore longtemps \u00e0 nous parler des choses difficiles, de la mort, de la disparition, de notre propre mort et de celle de la civilisation.\u00bb<\/p>\n<p>*Ed. Zo\u00e9 (1994), 176 p.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9dition 2013 des Myst\u00e8res de l\u2019UNIL a pris le c\u00e9l\u00e8bre paquebot comme m\u00e9taphore d\u2019une soci\u00e9t\u00e9 utopique naviguant sur des eaux dangereuses. Un mythe qui perdure: Allez savoir! avait trait\u00e9 de &hellip; <\/p>\n","protected":false},"author":825,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[39524,42129],"tags":[39521],"class_list":{"0":"post-4657","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-chronique","7":"category-no-54","8":"tag-david-spring"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/4657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/users\/825"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/comments?post=4657"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/4657\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media?parent=4657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/categories?post=4657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/tags?post=4657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}