{"id":23,"date":"2008-12-01T17:03:55","date_gmt":"2008-12-01T15:03:55","guid":{"rendered":"http:\/\/wp.unil.ch\/allezsavoir\/?p=23"},"modified":"2012-05-15T16:56:19","modified_gmt":"2012-05-15T14:56:19","slug":"admettons-un-instant-que-darwin-se-soit-trompe","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/allezsavoir\/admettons-un-instant-que-darwin-se-soit-trompe\/","title":{"rendered":"Admettons un instant que Darwin se soit tromp\u00e9\u2026 Que dit la Bible \u00e0 propos de la Gen\u00e8se?"},"content":{"rendered":"<figure id=\"attachment_2313\" aria-describedby=\"caption-attachment-2313\" style=\"width: 530px\" class=\"wp-caption alignnone\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2313\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2008\/12\/dinosaures.jpg\" alt=\"\" width=\"530\" height=\"260\" \/><figcaption id=\"caption-attachment-2313\" class=\"wp-caption-text\">\u00a9 AlienCat - fotolia.com<\/figcaption><\/figure>\n<p><em>A double titre, 2009 sera l&rsquo;ann\u00e9e Charles Darwin. Nous c\u00e9l\u00e9brerons le bicentenaire de sa naissance, le 12 f\u00e9vrier 2009, et les 150 ans de son ouvrage \u00abL&rsquo;Origine des esp\u00e8ces\u00bb. La pol\u00e9mique avec les cr\u00e9ationnistes est programm\u00e9e. Profitons-en pour relire l&rsquo;Ancien Testament avec Thomas R\u00f6mer, un sp\u00e9cialiste de l&rsquo;UNIL. Surprise: on d\u00e9couvre que la Bible raconte deux origines du monde inconciliables. Bonne nouvelle pour Darwin!<\/em><\/p>\n<p>Et si Darwin avait tort? Et si la Bible disait vrai sur la cr\u00e9ation du monde? En v\u00e9rit\u00e9, plusieurs arguments tr\u00e8s s\u00e9rieux militent pour ce point de vue. D\u2019abord, le Livre Saint a 2500 ans; c\u2019est beaucoup plus ancien que \u00abL\u2019Origine des esp\u00e8ces\u00bb, qui fut publi\u00e9 le 24 novembre 1859 et dont on c\u00e9l\u00e9brera l\u2019an prochain les 150 petites ann\u00e9es d\u2019existence.<\/p>\n<p>Ensuite, l\u2019Ancien Testament est \u00e0 lui seul trois fois plus gros que le petit pav\u00e9 de Darwin: plus de 2000 pages dans une traduction courante, contre \u00e0 peine plus de 600 pour le pensum du biologiste anglais.<\/p>\n<p>Troisi\u00e8mement, la Bible est au sommet des ventes depuis des temps imm\u00e9moriaux. C\u2019est m\u00eame l\u2019ouvrage le plus lu dans le monde entier, loin devant Harry Potter, \u00abMillenium\u00bb ou le \u00abDa Vinci Code \u00bb. Et si loin des livres de Darwin que c\u2019en est humiliant. D\u2019ailleurs, \u00abL\u2019origine des esp\u00e8ces\u00bb n\u2019appara\u00eet dans aucun classement commercial.<\/p>\n<h3>Il y a deux Gen\u00e8ses dans la Bible<\/h3>\n<p>Malgr\u00e9 ces \u00e9vidences, des esprits chagrins doutent encore. Parmi eux, Thomas R\u00f6mer, qu\u2019on dit grand sp\u00e9cialiste de l\u2019Ancien Testament et qui enseigne \u00e0 la Facult\u00e9 de th\u00e9ologie de l\u2019UNIL et au Coll\u00e8ge de France. Ce professeur affirme que la Gen\u00e8se est incoh\u00e9rente; que si on la lit \u00e0 la lettre, l\u2019histoire de la naissance du monde ne tient pas debout.<\/p>\n<p>Son argument principal est le suivant : la Gen\u00e8se propose deux r\u00e9cits de la cr\u00e9ation du monde et non pas un. Le premier va jusqu\u2019au chapitre II, verset 4; le deuxi\u00e8me commence \u00e0 ce point jusqu\u2019\u00e0 la fin du chapitre III. Entre ces deux r\u00e9cits, et parfois m\u00eame \u00e0 l\u2019int\u00e9rieur de chaque r\u00e9cit, il y aurait une s\u00e9rie de contradictions et de bizarreries flagrantes dans la Bible.<\/p>\n<h3>L\u2019homme a-t-il \u00e9t\u00e9 cr\u00e9\u00e9 avant la femme ou en m\u00eame temps?<\/h3>\n<p>Au chapitre I verset 27 de la Gen\u00e8se, il est \u00e9crit: \u00abDieu cr\u00e9a l\u2019homme \u00e0 son image, \u00e0 l\u2019image de Dieu il le cr\u00e9a; m\u00e2le et femelle il les cr\u00e9a.\u00bb Une dizaine de versets plus loin, dans le chapitre suivant, il est \u00e9crit: \u00abLe Seigneur Dieu modela l\u2019homme avec de la poussi\u00e8re prise du sol. Il insuffla dans ses narines l\u2019haleine de vie, et l\u2019homme devint un \u00eatre vivant.\u00bb Eh bien, dans ces deux brefs passages, Thomas R\u00f6mer parvient \u00e0 voir cinq \u00e9l\u00e9ments contradictoires.<\/p>\n<p><strong>Contradiction n\u00b0 1:<\/strong> ces deux passages racontent la naissance de la femme \u00e0 deux moments diff\u00e9rents. \u00abDans le premier, l\u2019homme et la femme apparaissent en m\u00eame temps; Dieu cr\u00e9e le couple humain, rel\u00e8ve le professeur. Or, dans le deuxi\u00e8me passage, le Seigneur commence par cr\u00e9er un seul \u00eatre.\u00bb<\/p>\n<p>Dans ce que Thomas R\u00f6mer appelle \u00able deuxi\u00e8me r\u00e9cit\u00bb, la femme arrive en dernier. Adam commence par s\u2019ennuyer dans le jardin d\u2019Eden, puis Dieu compatit et cherche \u00e0 lui faire \u00abune aide\u00bb. Il pense d\u2019abord \u00e0 cr\u00e9er les animaux pour lui tenir compagnie; mais le pauvre homme ne trouve pas chaussure \u00e0 son pied. Alors Dieu l\u2019endort et lui enl\u00e8ve une c\u00f4te qu\u2019il \u00abtransforme\u00bb en une femme.<\/p>\n<h3>Adam a-t-il \u00e9t\u00e9 cr\u00e9\u00e9 avant ou apr\u00e8s les animaux?<\/h3>\n<p><strong>Contradiction n\u00b0 2: <\/strong>dans le premier passage, le couple humain est cr\u00e9\u00e9 \u00ab\u00e0 l\u2019image de Dieu\u00bb \u2013 le texte dit aussi selon sa \u00abressemblance\u00bb; dans le deuxi\u00e8me, lorsque le Seigneur cr\u00e9e Adam seul, cette r\u00e9f\u00e9rence n\u2019appara\u00eet plus.<\/p>\n<p><strong>Contradiction n\u00b0 3:<\/strong> dans le premier r\u00e9cit, Dieu s\u2019appelle \u00abDieu\u00bb, soit \u00abElohim \u00bb dans le texte original; dans le deuxi\u00e8me r\u00e9cit, il s\u2019appelle \u00abYahv\u00e9\u00bb, qu\u2019on traduit en fran\u00e7ais par \u00able Seigneur \u00bb.<\/p>\n<p><strong>Contradiction n\u00b0 4:<\/strong> lorsque le couple humain appara\u00eet dans le premier r\u00e9cit, tous les animaux sont d\u00e9j\u00e0 cr\u00e9\u00e9s; les \u00eatres humains arrivent donc en dernier. Mais dans le chapitre suivant, lorsqu\u2019Adam \u00e9merge de sa glaise, il n\u2019y a sur la Terre, dit le texte, \u00abencore aucun arbuste des champs et aucune herbe n\u2019avait encore germ\u00e9\u00bb.<\/p>\n<p><strong>Contradiction n\u00b0 5, enfin: <\/strong>le couple humain prend vie par la seule parole divine, tandis que l\u2019homme solitaire est model\u00e9 par les mains du Cr\u00e9ateur \u00abavec de la poussi\u00e8re prise du sol\u00bb.<\/p>\n<h3>L\u2019homme est-il vraiment sup\u00e9rieur aux animaux?<\/h3>\n<p>La chasse aux contradictions de Thomas R\u00f6mer ne s\u2019arr\u00eate pas l\u00e0. Il examine d\u2019autres passages et s\u2019amuse \u00e0 pointer une foule de probl\u00e8mes suppl\u00e9mentaires.<\/p>\n<p>Lorsque le Cr\u00e9ateur s\u2019appr\u00eate \u00e0 cr\u00e9er l\u2019homme et la femme d\u2019un seul coup, il d\u00e9crit la mission de l\u2019\u00eatre humain en disant \u00abqu\u2019il soumette les poissons de la mer, les oiseaux du ciel, les bestiaux, toute la terre et toutes les petites b\u00eates qui remuent sur la terre!\u00bb<\/p>\n<p>Mais lorsque \u00able Seigneur Dieu\u00bb cr\u00e9e Adam dans le deuxi\u00e8me r\u00e9cit, le texte dit simplement que le Cr\u00e9ateur \u00ab\u00e9tablit\u00bb l\u2019\u00eatre humain dans le jardin d\u2019Eden \u00abpour cultiver le sol et le garder\u00bb.<\/p>\n<p>Une diff\u00e9rence qui suscite ce commentaire au professeur: \u00abDans le premier r\u00e9cit, le texte instaure une sup\u00e9riorit\u00e9 des hommes sur les animaux. Dieu attribue une sorte d\u2019ascendance royale \u00e0 l\u2019homme sur le r\u00e8gne animal. Dans le deuxi\u00e8me r\u00e9cit, Dieu donne aux animaux un r\u00f4le de compagnon pour Adam. Cela signifie qu\u2019homme et animaux ne sont pas si diff\u00e9rents, qu\u2019ils sont au m\u00eame niveau.\u00bb<\/p>\n<h3>Pourquoi, pourquoi, pourquoi?<\/h3>\n<p>Et puis, comment se fait-il que le jour et les plantes sont cr\u00e9\u00e9s avant le soleil? Comment l\u2019humanit\u00e9 a-t-elle pu se reproduire puisqu\u2019Adam et Eve n\u2019ont fait que des gar\u00e7ons? Ca\u00efn a-t-il couch\u00e9 avec sa m\u00e8re apr\u00e8s avoir tu\u00e9 son fr\u00e8re? Pourquoi Ca\u00efn a-t-il peur d\u2019\u00eatre tu\u00e9 par quelqu\u2019un apr\u00e8s avoir tu\u00e9 Abel, alors que ne vivent encore que trois \u00eatres humains sur terre? Pourquoi Dieu prot\u00e8ge-t-il Ca\u00efn le meurtrier quelques lignes apr\u00e8s l\u2019avoir maudit?<\/p>\n<p>Et encore: qui sont ces \u00abg\u00e9ants\u00bb, qui apparaissent au chapitre VI et habitent la Terre au moment o\u00f9 Dieu d\u00e9cide pour la premi\u00e8re fois d\u2019an\u00e9antir l\u2019humanit\u00e9? Pourquoi les humains parlent-ils plusieurs langues au chapitre X, puis une seule au chapitre XI? Pourquoi est-il \u00e9crit que le D\u00e9luge a dur\u00e9 50 jours dans une ligne et 140 jours dans une autre? Etc., etc&#8230; \u00abSi l\u2019on dressait la liste de toutes les incoh\u00e9rences de la Bible, on pourrait \u00e9crire un livre entier\u00bb, dit Thomas R\u00f6mer avec malice.<\/p>\n<h3>M\u00eame l\u2019Eglise h\u00e9site \u00e0 prendre la Bible au pied de la lettre<\/h3>\n<p>Il y a longtemps que cette fa\u00e7on de mettre en doute la v\u00e9rit\u00e9 biblique a com- menc\u00e9. Au d\u00e9but du XVIIe si\u00e8cle d\u00e9j\u00e0, Galil\u00e9e s\u2019acharne \u00e0 instiller le doute. Il affirme que la Terre n\u2019est pas un simple plateau surmont\u00e9 d\u2019une cloche \u00e0 fromage, comme le racontent les Ecritures.<\/p>\n<p>\u00abApr\u00e8s lui, l\u2019Eglise a commenc\u00e9 \u00e0 se dire qu\u2019on ne pouvait peut-\u00eatre pas prendre toute la Bible \u00e0 la lettre, dit Thomas R\u00f6mer. Au XVIIIe si\u00e8cle, on s\u2019int\u00e9resse \u00e0 la formation du Pentateuque, et on s\u2019aper\u00e7oit que les cinq premiers livres de l\u2019Ancien Testament se composent de diff\u00e9rents documents. Cette constatation est \u00e0 l\u2019origine de l\u2019hypoth\u00e8se, ult\u00e9rieure, que la Bible a \u00e9t\u00e9 \u00e9crite par plusieurs r\u00e9dacteurs \u00e0 diff\u00e9rentes \u00e9poques.\u00bb<\/p>\n<h3>Un pot-pourri de r\u00e9cits ant\u00e9rieurs<\/h3>\n<p>Thomas R\u00f6mer affirme ainsi que la Gen\u00e8se n\u2019a pas \u00e9t\u00e9 r\u00e9dig\u00e9e par Mo\u00efse sous la dict\u00e9e de Dieu sur le mont Sina\u00ef. \u00abComme le Pentateuque et l\u2019ensemble de l\u2019Ancien Testament, le r\u00e9cit de la cr\u00e9ation est une compilation de plusieurs histoires, un pot-pourri de toutes sortes de conceptions de l\u2019origine du monde.\u00bb<\/p>\n<p>Un exemple parmi d\u2019autres : la Bible raconte que Dieu cr\u00e9e le monde \u00e0 partir d\u2019un oc\u00e9an primordial, dont il partage les eaux. \u00abL\u2019id\u00e9e que la naissance de l\u2019univers a pass\u00e9 par une s\u00e9paration se retrouve dans les traditions \u00e9gyptiennes, babyloniennes et grecques. Chez les Egyptiens, le ciel et la terre forment un couple qui fait l\u2019amour continuellement et qu\u2019il faut s\u00e9parer pour que le monde puisse na\u00eetre.\u00bb<\/p>\n<p>Chez les Grecs, le ciel Ouranos \u00e9touffe la Terre Gaia de son poids avant que les Titans, les toutes premi\u00e8res divinit\u00e9s de la mythologie, ne coupent son sexe pour pouvoir sortir du ventre de leur m\u00e8re.<\/p>\n<p>Quant au r\u00e9cit du D\u00e9luge, on le trouve dans plusieurs histoires ant\u00e9rieures \u00e0 la Bible: \u00abLe r\u00e9cit biblique reprend de nombreuses traditions tout en les r\u00e9interpr\u00e9tant, dit Thomas R\u00f6mer. Dans l\u2019\u00e9pop\u00e9e de Gilgamesh, les dieux d\u00e9clenchent le d\u00e9luge par pur caprice, comme pour s\u2019amuser. La Gen\u00e8se reprend la m\u00eame histoire en donnant une raison moins arbitraire. Dieu d\u00e9truit l\u2019humanit\u00e9 parce qu\u2019elle est devenue mauvaise.\u00bb<\/p>\n<h3>La v\u00e9rit\u00e9 peut-elle avoir des zones d\u2019ombre?<\/h3>\n<p>Que r\u00e9pondre \u00e0 tout cela? L\u2019intention du professeur de th\u00e9ologie lausannois est claire: selon lui, \u00abil est totalement absurde de prendre la Bible \u00e0 la lettre\u00bb. Que peut bien r\u00e9torquer un cr\u00e9ationniste contre cette vision, qui enl\u00e8ve \u00e0 la Bible toute r\u00e9alit\u00e9? Thomas R\u00f6mer donne lui-m\u00eame des pistes : \u00abContrairement aux Anciens ou \u00e0 la tradition juive, la tradition chr\u00e9tienne refuse que la Bible puisse comporter des faits ou des id\u00e9es contradictoires. Pour les fondamentalistes, la v\u00e9rit\u00e9 est forc\u00e9ment coh\u00e9rente. Elle ne peut pas avoir de zones d\u2019ombre.\u00bb<\/p>\n<p>Voil\u00e0 donc ce qu\u2019un bon lecteur de la Bible doit faire, lorsqu\u2019il est confront\u00e9 au mitraillage de remises en question des sp\u00e9cialistes : trouver la logique obligatoire des textes; r\u00e9v\u00e9ler une coh\u00e9rence qui n\u2019appara\u00eet pas aux sceptiques. La Gen\u00e8se comprend deux r\u00e9cits? \u00abLes lecteurs litt\u00e9raux de la Bible r\u00e9pondent que la premi\u00e8re partie raconte la naissance du monde dans ses grandes lignes, tandis que la deuxi\u00e8me reprend l\u2019histoire en donnant plus de d\u00e9tails.\u00bb<\/p>\n<p>Le r\u00e9cit de la cr\u00e9ation ne parle pas des dinosaures et de leur disparition scientifiquement prouv\u00e9e? \u00abCela veut dire que ces animaux ont disparu pendant le D\u00e9luge.\u00bb Comment Ca\u00efn a-t-il pu avoir un fils dans un monde sans autre femme que sa m\u00e8re? \u00abDieu a cr\u00e9\u00e9 des femmes \u00e0 un moment donn\u00e9&#8230;\u00bb<\/p>\n<h3>Une intime conviction<\/h3>\n<p>Le fid\u00e8le qui croit en la lettre biblique n\u2019a cependant pas besoin d\u2019aller trop loin pour d\u00e9fier les chercheurs de contradictions. De la bouche m\u00eame de Thomas R\u00f6mer, \u00ables cr\u00e9ationnistes ont un argument imbattable: tout est possible \u00e0 Dieu\u00bb. Pourquoi donc se casser la t\u00eate davantage? Pourquoi m\u00eame s\u2019attarder sur les textes plus qu\u2019il ne faut? \u00abLe cr\u00e9ationnisme n\u2019a pas v\u00e9ritablement de th\u00e9orie, dit Thomas R\u00f6mer, et la plupart des personnes qui croient en une lecture litt\u00e9rale de la Bible ne connaissent pas le texte avec pr\u00e9cision. Ils n\u2019estiment pas en avoir besoin. Ils sont simplement convaincus que la Bible a raison et que la science a tort.\u00bb<\/p>\n<p>Mais la science elle-m\u00eame n\u2019a-t-elle pas montr\u00e9 son imperfection? \u00abLa th\u00e9orie de l\u2019\u00e9volution a connu plusieurs corrections apr\u00e8s Darwin, les cr\u00e9ationnistes jouent aussi sur ces remises en question.\u00bb<\/p>\n<p>Eh oui, si la science elle-m\u00eame d\u00e9montre que la science se trompe, pourquoi la croire&#8230;?<\/p>\n<p style=\"text-align: right\">Pierre-Louis Chantre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A double titre, 2009 sera l&rsquo;ann\u00e9e Charles Darwin. Nous c\u00e9l\u00e9brerons le bicentenaire de sa naissance, le 12 f\u00e9vrier 2009, et les 150 ans de son ouvrage \u00abL&rsquo;Origine des esp\u00e8ces\u00bb. La &hellip; <\/p>\n","protected":false},"author":47,"featured_media":2313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[40,34,32],"tags":[42],"class_list":{"0":"post-23","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-no-43","8":"category-religion","9":"category-technologie","10":"tag-pierre-louis-chantre"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/23\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media\/2313"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media?parent=23"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/categories?post=23"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/tags?post=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}