{"id":12359,"date":"2022-02-23T08:14:00","date_gmt":"2022-02-23T06:14:00","guid":{"rendered":"https:\/\/wp.unil.ch\/allezsavoir\/?p=12359"},"modified":"2022-02-23T11:17:55","modified_gmt":"2022-02-23T09:17:55","slug":"on-mange-quoi-aujourdhui","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/allezsavoir\/on-mange-quoi-aujourdhui\/","title":{"rendered":"On mange quoi, aujourd\u2019hui?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"401\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/SalvatoreBevilacqua_79.jpg\" alt=\"\" class=\"wp-image-12280\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/SalvatoreBevilacqua_79.jpg 600w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/SalvatoreBevilacqua_79-389x260.jpg 389w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption>Salvatore Bevilacqua. Chercheur associ\u00e9 \u00e0 l\u2019Institut des humanit\u00e9s en m\u00e9decine UNIL-CHUV. Photographi\u00e9 ici dans les abattoirs de Malley, vou\u00e9s \u00e0 la destruction. Nicole Chuard \u00a9 UNIL<\/figcaption><\/figure>\n\n\n\n<p><em>Darne de saumon, soupe miso, steak argentin ou guacamole? Le choix ne manque pas de nos jours. Mais en vit-on mieux? Le point avec l\u2019anthropologue Salvatore Bevilacqua, chercheur associ\u00e9 \u00e0 l\u2019Institut des humanit\u00e9s en m\u00e9decine, charg\u00e9 de cours \u00e0 la Facult\u00e9 de biologie et m\u00e9decine et chef du projet \u00abMalley en quartiers\u00bb, qui retrace l\u2019histoire des abattoirs de Lausanne.<\/em><\/p>\n\n\n\n<p><strong>En Suisse, il semble plus facile de se nourrir actuellement qu\u2019au Moyen \u00c2ge. Une r\u00e9alit\u00e9?<\/strong><\/p>\n\n\n\n<p>La comparaison est complexe. Au Moyen \u00c2ge, le souci de la grande majorit\u00e9 de la population \u00e9tait de manger \u00e0 sa faim et survivre aux disettes, tandis que l\u2019\u00e9lite avait acc\u00e8s \u00e0 des nourritures abondantes, prestigieuses et plus vari\u00e9es. \u00c0 l\u2019inverse, l\u2019hyperchoix li\u00e9 \u00e0 la disponibilit\u00e9 alimentaire de nos soci\u00e9t\u00e9s, o\u00f9 l\u2019on \u00abmange sans faim\u00bb, fait \u00e9merger des probl\u00e8mes de sant\u00e9 publique sp\u00e9cifiques, telles l\u2019ob\u00e9sit\u00e9 ou l\u2019orthorexie. Toutes proportions gard\u00e9es, le choix alimentaire \u00e9tait peut-\u00eatre plus \u00ab\u00e9vident\u00bb au Moyen \u00c2ge, dans la mesure o\u00f9 les repas \u00e9taient fortement encadr\u00e9s par les r\u00e8gles sociales et religieuses.<\/p>\n\n\n\n<p><strong>Parmi nos exc\u00e8s, on trouve la consommation de viande, disent les m\u00e9decins et les \u00e9cologistes. Quelles r\u00e9percussions cette affirmation a-t-elle sur les comportements alimentaires actuels?<\/strong><\/p>\n\n\n\n<p>Si l\u2019on regarde les quantit\u00e9s moyennes consomm\u00e9es par personne en Suisse, la consommation de viande est en d\u00e9clin. De 31,5 kg par an en 1950, elle passe \u00e0 60 kg en 1987, pour tomber \u00e0 environ 51 kg en 2019. Durant les Trente Glorieuses, la viande, devenant accessible aux classes populaires, \u00e9tait tr\u00e8s pris\u00e9e car associ\u00e9e, alors, \u00e0 l\u2019aisance mat\u00e9rielle, \u00e0 la force virile et \u00e0 une bonne sant\u00e9. Depuis, les d\u00e9couvertes et recommandations m\u00e9dicales, pointant notamment les risques cardiaques ou canc\u00e9rig\u00e8nes d\u2019un r\u00e9gime tr\u00e8s carn\u00e9, nous incitent \u00e0 consommer moins de viande rouge (b\u0153uf, agneau, cheval) et transform\u00e9e. Toutefois, ce recul est contrebalanc\u00e9 par une hausse de la consommation de viande blanche, en particulier la volaille, plus \u00e9conomique et consid\u00e9r\u00e9e plus saine.<\/p>\n\n\n\n<p><strong>Quels facteurs d\u00e9terminants initient ces changements ?<\/strong><\/p>\n\n\n\n<p>Les scandales sanitaires, comme la vache folle, ont \u00e9veill\u00e9 une suspicion sur les produits carn\u00e9s, industriels notamment, devenus porteurs de risques pour la sant\u00e9, mais aussi pour la plan\u00e8te \u00e0 cause du poids de l\u2019\u00e9levage intensif en termes d\u2019\u00e9mission de CO<sub>2<\/sub>. Les arguments en faveur d\u2019une baisse de consommation de viande invoquent la pr\u00e9vention de la sant\u00e9, la pr\u00e9servation de la biodiversit\u00e9 et la lutte contre le changement climatique. S\u2019y ajoute l\u2019\u00e9volution des sensibilit\u00e9s sociales par rapport \u00e0 la souffrance animale, illustr\u00e9e par le v\u00e9ganisme, forme de consommation, ou style de vie, renon\u00e7ant \u00e0 tout produit issu de l\u2019exploitation animale. Ces repr\u00e9sentations n\u00e9gatives et les controverses qui entourent aujourd\u2019hui la viande soulignent son statut ambivalent: aliment de choix recherch\u00e9 mais jug\u00e9 nuisible, voire immoral. Or, la consommation de viande n\u2019est pas pr\u00e8s de dispara\u00eetre. Les Suisses en avaleraient trois fois plus que la quantit\u00e9 recommand\u00e9e selon l\u2019enqu\u00eate menuCH.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"800\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/alimentation_79_1.jpg\" alt=\"\" class=\"wp-image-12178\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/alimentation_79_1.jpg 796w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/alimentation_79_1-259x260.jpg 259w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/alimentation_79_1-250x250.jpg 250w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2022\/02\/alimentation_79_1-768x772.jpg 768w\" sizes=\"auto, (max-width: 796px) 100vw, 796px\" \/><figcaption>Durant les Trente Glorieuses, la viande, accessible aux classes populaires, \u00e9tait tr\u00e8s pris\u00e9e. Ici, le comptoir de la boucherie de la Migros de Courtepin (FR) en 1965.\n\u00a9\u2009Str\/Keystone<\/figcaption><\/figure>\n\n\n\n<p><strong>Avaler de la chair animale est pourtant devenu anxiog\u00e8ne&#8230;<\/strong><\/p>\n\n\n\n<p>Le sacrifice alimentaire animal a toujours \u00e9t\u00e9 source d\u2019anxi\u00e9t\u00e9. La crise sanitaire de la vache folle a raviv\u00e9 ce fait. La critique des mesures adopt\u00e9es, notamment l\u2019insuffisance du contr\u00f4le des fili\u00e8res de l\u2019industrie de la viande, a g\u00e9n\u00e9r\u00e9 une crise de confiance et, par cons\u00e9quent, un besoin de transparence des consommateurs, par ailleurs de plus en plus d\u00e9sorient\u00e9s par la profusion et la versatilit\u00e9 des messages promettant, dans nos soci\u00e9t\u00e9s de surabondance, une alimentation saine, s\u00fbre ou id\u00e9ale.&nbsp;<\/p>\n\n\n\n<p><strong>En raison de l\u2019hyperchoix donc.<\/strong><\/p>\n\n\n\n<p>Oui, l\u2019hyperchoix met l\u2019individu en situation de devoir \u00e9valuer constamment et d\u00e9cider ce qui est bon ou mauvais \u00e0 ing\u00e9rer, cela en g\u00e9rant l\u2019information pl\u00e9thorique produite par les m\u00e9dias, les r\u00e9seaux sociaux et les sp\u00e9cialistes. Cette r\u00e9flexivit\u00e9, plus marqu\u00e9e dans les classes moyennes, perm\u00e9ables aux discours de pr\u00e9vention, \u00e9loigne le consommateur d\u2019une certaine spontan\u00e9it\u00e9. \u00c0 la limite, faire ses courses devient pour certains une sorte de \u00abtravail\u00bb guid\u00e9 par des raisons d\u2019ordre nutritionnel, rel\u00e9guant peut-\u00eatre le go\u00fbt, le plaisir ou la convivialit\u00e9 au second plan.<\/p>\n\n\n\n<p><strong>Que dire de l\u2019impact de la m\u00e9decine sur nos assiettes?<\/strong><\/p>\n\n\n\n<p>En \u00abnutritionnalisant\u00bb l\u2019alimentation, le discours m\u00e9dical s\u2019est impos\u00e9 sur les cadres sociaux et religieux qui r\u00e9gulaient jadis les repas, dit Jean-Pierre Poulain. Lib\u00e9r\u00e9 des anciens carcans sociaux, mais plus seul, le mangeur actuel s\u2019en remet \u00e0 la rationalit\u00e9 m\u00e9dicale pour r\u00e9pondre \u00e0 ses pr\u00e9occupations. La  nutritionnalisation de l\u2019alimentation refl\u00e8te cette p\u00e9n\u00e9tration de l\u2019univers m\u00e9dical dans la vie quotidienne. Elle est int\u00e9gr\u00e9e \u00e0 l\u2019offre alimentaire via les informations pr\u00e9sentes sur les \u00e9tiquettes par exemple. All\u00e9gations nutritionnelles et de sant\u00e9, ingr\u00e9dients, origine, labels bio ou vegan r\u00e9pondent ainsi \u00e0 une demande de tra\u00e7abilit\u00e9 qui s\u00e9curise les consommateurs, d\u00e9voilant en filigrane les repr\u00e9sentations collectives des risques alimentaires hantant nos soci\u00e9t\u00e9s. <\/p>\n\n\n\n<p>\u00c0 consulter: <a rel=\"noreferrer noopener\" href=\"https:\/\/malleyenquartiers.ch\" data-type=\"URL\" data-id=\"malleyenquartiers.ch\" target=\"_blank\">malleyenquartiers.ch<\/a><\/p>\n\n\n\n<p>Article principal: <a href=\"https:\/\/wp.unil.ch\/allezsavoir\/?p=12355\" data-type=\"URL\" data-id=\"https:\/\/wp.unil.ch\/allezsavoir\/?p=12355\">Les petits plats des grands-ducs<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Darne de saumon, soupe miso, steak argentin ou guacamole? Le choix ne manque pas de nos jours. Mais en vit-on mieux? Le point avec l\u2019anthropologue Salvatore Bevilacqua, chercheur associ\u00e9 \u00e0 &hellip; <\/p>\n","protected":false},"author":825,"featured_media":12179,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[42198,35],"tags":[42181],"class_list":{"0":"post-12359","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-no-79","8":"category-societe","9":"tag-virginie-jobe-truffer"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/12359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/users\/825"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/comments?post=12359"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/12359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media\/12179"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media?parent=12359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/categories?post=12359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/tags?post=12359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}