{"id":1135,"date":"2007-12-18T19:26:38","date_gmt":"2007-12-18T17:26:38","guid":{"rendered":"http:\/\/wp.unil.ch\/allezsavoir\/?p=1135"},"modified":"2010-10-26T16:56:05","modified_gmt":"2010-10-26T14:56:05","slug":"on-sauve-des-prematures-de-plus-en-plus-petits","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/allezsavoir\/on-sauve-des-prematures-de-plus-en-plus-petits\/","title":{"rendered":"On sauve des pr\u00e9matur\u00e9s de plus en plus petits"},"content":{"rendered":"<p><a href=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2007\/12\/couveuse.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1175\" src=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2007\/12\/couveuse.jpg\" alt=\"On sauve des pr\u00e9matur\u00e9s de plus en plus petits\" width=\"530\" height=\"260\" srcset=\"https:\/\/wp.unil.ch\/allezsavoir\/files\/2007\/12\/couveuse.jpg 530w, https:\/\/wp.unil.ch\/allezsavoir\/files\/2007\/12\/couveuse-300x147.jpg 300w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/a><\/p>\n<p><em>A la fin des ann\u00e9es 1980, les p\u00e9diatres ne pouvaient rien faire pour un enfant n\u00e9 avant 28 semaines de grossesse. Aujourd\u2019hui, la fronti\u00e8re entre la vie et la mort est \u00e0 25 semaines. Voil\u00e0 qui en dit long sur les progr\u00e8s r\u00e9alis\u00e9s. D\u00e9sormais, les b\u00e9b\u00e9s qui voient le jour apr\u00e8s la 32 e semaine de gestation, ou qui p\u00e8sent plus de deux kilogrammes, ont un taux de survie identique \u00e0 celui des enfants n\u00e9s \u00e0 terme. Et beaucoup moins de handicaps qu\u2019on le croit. Bonne nouvelle, quand on sait qu\u2019un b\u00e9b\u00e9 sur 10 naissances est un pr\u00e9matur\u00e9.<\/em><\/p>\n<p>Dans quelle commune le premier b\u00e9b\u00e9 suisse de 2008 verra-t-il le jour? Comme chaque ann\u00e9e, les paris sont ouverts. Ce qui est s\u00fbr, c\u2019est qu\u2019il aura une chance sur dix d\u2019\u00eatre un pr\u00e9matur\u00e9. Il y a une vingtaine d\u2019ann\u00e9es, cette nouvelle aurait \u00e9t\u00e9 inqui\u00e9tante. Ce n\u2019est plus le cas aujourd\u2019hui.<\/p>\n<p>La surveillance de la m\u00e8re et du f\u0153tus ainsi que la prise en charge des nouveau-n\u00e9s avant terme ont fait de tels progr\u00e8s que la mortalit\u00e9 et les s\u00e9quelles ont consid\u00e9rablement diminu\u00e9. Tour d\u2019horizon des pr\u00e9jug\u00e9s \u00e0 revoir avec le n\u00e9onatologue Jean-Fran\u00e7ois Tolsa et Yvan Vial, obst\u00e9tricien, au CHUV.<\/p>\n<h2>1 &#8211; Tous les pr\u00e9matur\u00e9s sont des enfants \u00e0 haut risque<\/h2>\n<p>Bien au contraire. Aujourd\u2019hui, les b\u00e9b\u00e9s qui voient le jour apr\u00e8s la 32e semaine de gestation, ou qui p\u00e8sent plus de deux kilogrammes, ont un taux de survie identique \u00e0 celui des enfants n\u00e9s \u00e0 terme. Encore faut-il s\u2019entendre sur les mots. Une naissance est dite \u00ab\u00e0 terme\u00bb lorsqu\u2019elle se produit entre 37 et 42 semaines de grossesse.<\/p>\n<p>Tout b\u00e9b\u00e9 n\u00e9 \u00e0 moins de 37 semaines accomplies est donc consid\u00e9r\u00e9 comme pr\u00e9matur\u00e9. Sous ce terme se cachent toutefois des situations forts diff\u00e9rentes, qui d\u00e9pendent du stade de d\u00e9veloppement du f\u0153tus. On l\u2019imagine volontiers, la probl\u00e9matique n\u2019est pas la m\u00eame si l\u2019accouchement a lieu dans une p\u00e9riode assez proche du terme, entre la 32e et la 37e semaine de gestation, ou s\u2019il se produit entre 28 et 32 semaines. On parle alors de \u00abgrand pr\u00e9matur\u00e9\u00bb, et de \u00abpr\u00e9matur\u00e9 extr\u00eame\u00bb quand le nouveau-n\u00e9 arrive apr\u00e8s 24 \u00e0 28 semaines. \u00abIl ne faut toutefois pas banaliser les risques d\u2019une naissance entre 32 et 37 semaines\u00bb, pr\u00e9cise Jean-Fran\u00e7ois Tolsa, m\u00e9decin-chef ad interim de la Division de n\u00e9onatologie du CHUV.<\/p>\n<p><strong>La \u00ablimite de viabilit\u00e9\u00bb<\/strong><\/p>\n<p>On peut aussi classer les b\u00e9b\u00e9s en fonction de leur poids \u00e0 la naissance. Cet \u00e9l\u00e9ment a \u00abaussi une influence sur le pronostic\u00bb, explique le sp\u00e9cialiste de n\u00e9onatologie. Mais ce facteur, qui peut \u00eatre d\u00fb \u00e0 un retard de croissance intra-ut\u00e9rin, est moins important que la dur\u00e9e de gestation, p\u00e9riode pendant laquelle on assiste \u00e0 \u00abla maturation des organes\u00bb du f\u0153tus.<\/p>\n<p>A partir de la 12e semaine et jusqu\u2019\u00e0 terme, ce dernier acquiert en effet ce que les m\u00e9decins nomment son \u00abindividualisation physiologique\u00bb: dans l\u2019ut\u00e9rus, il bouge, il fait des mouvements respiratoires, il r\u00e8gle sa circulation, il secr\u00e8te des hormones, il avale et il urine. Vers la 25e semaine, ce processus est suffisamment avanc\u00e9 pour que, dans certains cas, la vie extra-ut\u00e9rine soit possible. Les sp\u00e9cialistes estiment toutefois qu\u2019il s\u2019agit l\u00e0 de la \u00ablimite de viabilit\u00e9\u00bb.<\/p>\n<p><strong>Amilia, ce \u00abb\u00e9b\u00e9 miracle\u00bb de 284 grammes<\/strong><\/p>\n<p>Certes, il est parfois possible d\u2019aller au-del\u00e0, comme le montre la minuscule Amilia, n\u00e9e en octobre 2006, au Baptist Children\u2019s Hospital de Miami. Ce \u00abb\u00e9b\u00e9 miracle\u00bb, selon les termes des m\u00e9decins am\u00e9ricains qui l\u2019ont prise en charge, a vu le jour apr\u00e8s 22 semaines de grossesse et, \u00e0 sa naissance, elle ne mesurait que 24,1 centim\u00e8tres, et ne pesait que 284 grammes!<\/p>\n<p>\u00abC\u2019est l\u2019exception qui confirme la r\u00e8gle\u00bb, commente Yvan Vial, responsable  de l\u2019Unit\u00e9 \u00e9chographie et m\u00e9decine f\u0153tale du CHUV. Ce n\u2019est d\u2019ailleurs sans doute pas un hasard si ce record a \u00e9t\u00e9 enregistr\u00e9 aux Etats-Unis, car, dans ce pays, la \u00abpression m\u00e9dico-l\u00e9gale est importante\u00bb pour maintenir en vie les patients, m\u00eame dans des cas a priori d\u00e9sesp\u00e9r\u00e9s, pr\u00e9cise l\u2019obst\u00e9tricien. Amilia a eu de la chance car \u00e0 cet \u00e2ge-l\u00e0, \u00abla majorit\u00e9 des enfants d\u00e9c\u00e8de ou garde des s\u00e9quelles\u00bb.<\/p>\n<h2>2 &#8211; Un grand pr\u00e9matur\u00e9 souffrira plus tard de graves handicaps<\/h2>\n<p>Une fois encore, tout d\u00e9pend du degr\u00e9 de pr\u00e9maturit\u00e9. Chez les enfants n\u00e9s avant terme, la principale difficult\u00e9 est \u00abl\u2019adaptation du cerveau\u00bb, explique Jean-Fran\u00e7ois Tolsa. Cet organe ne doit souffrir ni d\u2019un manque d\u2019oxyg\u00e8ne, ni d\u2019une insuffisance de perfusion sanguine \u2013 lesquels sont li\u00e9s au d\u00e9veloppement des syst\u00e8mes cardiovasculaire et pulmonaire. Ce probl\u00e8me \u00abest le m\u00eame pour toutes les classes de pr\u00e9matur\u00e9s, ajoute le m\u00e9decin, mais les risques augmentent en fonction du degr\u00e9 de pr\u00e9maturit\u00e9\u00bb.<\/p>\n<p>Les enfants n\u00e9s entre 22 et 23 semaines ont ainsi un risque de d\u00e9c\u00e9der \u00e0 la naissance estim\u00e9 \u00e0 environ 98%. Mais ces cas sont tellement rares \u00abque l\u2019on n\u2019a pas de chiffres exacts\u00bb, souligne le sp\u00e9cialiste de n\u00e9onatologie. En revanche, entre 24 et 28 semaines, 30 \u00e0 80% des enfants survivent \u2013 un taux qui atteint 90 \u00e0 95% entre 28 et 32 semaines et 97% au-del\u00e0 de 34 semaines.<\/p>\n<p><strong>Des progr\u00e8s spectaculaires<\/strong><\/p>\n<p>On peut mesurer la vitesse des progr\u00e8s accomplis lorsque Jean-Fran\u00e7ois Tolsa pr\u00e9cise que, pour ces pr\u00e9matur\u00e9s extr\u00eames, \u00abentre 1980 et 2000, le taux de mortalit\u00e9 est pass\u00e9, \u00e0 Lausanne, de 60% \u00e0 20%\u00bb. \u00abLorsque j\u2019ai commenc\u00e9 ma carri\u00e8re \u00e0 la fin des ann\u00e9es 1980, rench\u00e9rit Yvan Vial, les p\u00e9diatres disaient qu\u2019ils ne pouvaient rien faire lorsqu\u2019ils se trouvaient face \u00e0 un enfant n\u00e9 avant 28 semaines de grossesse. Aujourd\u2019hui, on en est \u00e0 25 semaines.\u00bb Trois semaines de diff\u00e9rence, cela peut para\u00eetre peu. Mais \u00aben termes de maturit\u00e9 de l\u2019enfant, pr\u00e9cise l\u2019obst\u00e9tricien, c\u2019est \u00e9norme et \u00e0 ce stade, chaque jour gagn\u00e9 est un bon jour\u00bb.<\/p>\n<p>Reste la d\u00e9licate question du devenir de ces enfants. \u00abLorsque le CHUV a ouvert son premier service de n\u00e9onatologie, dans les ann\u00e9es 1960, on s\u2019est pos\u00e9 la question\u00bb, pr\u00e9cise Jean-Fran\u00e7ois Tolsa. D\u00e8s 1971, les professeurs Louis Samuel Prod\u2019hom et Andr\u00e9 Calame ont ainsi cr\u00e9\u00e9 une unit\u00e9 charg\u00e9e de \u00absuivre l\u2019\u00e9volution de ces enfants n\u00e9s trop t\u00f4t; c\u2019\u00e9tait alors la premi\u00e8re en Europe\u00bb.<\/p>\n<p><strong>Peu de handicaps s\u00e9v\u00e8res<\/strong><\/p>\n<p>Les pr\u00e9matur\u00e9s y sont r\u00e9guli\u00e8rement suivis \u00e0 des \u00e2ges cl\u00e9s: \u00e0 6, 12 et 18 mois, puis \u00e0 3, 5 et 9 ans. Gr\u00e2ce \u00e0 cette surveillance, on peut aujourd\u2019hui conclure que, \u00abselon l\u2019\u00e2ge de gestation de d\u00e9part, 3 \u00e0 5% des survivants souffrent de handicaps s\u00e9v\u00e8res tels que des infirmit\u00e9s d\u2019origine c\u00e9r\u00e9brale ou de graves troubles du d\u00e9veloppement. C\u2019est peu en absolu, constate le sp\u00e9cialiste de n\u00e9onatologie, mais c\u2019est encore trop et nous devons rester humbles et modestes.\u00bb<\/p>\n<p>Quant aux handicaps dits \u00abmineurs\u00bb &#8211; troubles l\u00e9gers de la vision et de l\u2019audition, troubles des apprentissages, etc. &#8211; \u00abon pensait auparavant qu\u2019ils affectaient 15 \u00e0 20% des enfants. Aujourd\u2019hui, on parle de 30 \u00e0 40%.\u00bb La diff\u00e9rence tient sans doute essentiellement \u00e0 la d\u00e9finition du trouble mineur, que Jean-Fran\u00e7ois Tolsa juge \u00abimpr\u00e9cise\u00bb. Elle \u00e9volue en outre au cours du temps: un enfant consid\u00e9r\u00e9 aujourd\u2019hui comme hyperactif \u00e9tait, il y a vingt ans, tout simplement r\u00e9put\u00e9 turbulent.<\/p>\n<h2>3 &#8211; A l\u2019adolescence, les pr\u00e9matur\u00e9s ont des difficult\u00e9s d\u2019apprentissage<\/h2>\n<p>Ce n\u2019est pas ce qui ressort de la th\u00e8se de Barbara Monget, chercheuse \u00e0 la Facult\u00e9 de biologie et de m\u00e9decine de l\u2019UNIL qui a consacr\u00e9 son travail de doctorat au devenir, \u00e0 l\u2019adolescence, des pr\u00e9matur\u00e9s. Parmi les 246 enfants pesant moins de 1500 grammes (ce qui correspond g\u00e9n\u00e9ralement \u00e0 ceux qui ont vu le jour avant 28 \u00e0 30 semaines de gestation), n\u00e9s aux CHUV et hospitalis\u00e9s dans la division de n\u00e9onatologie entre 1976 et 1981, elle en a examin\u00e9 105, qui ne souffraient d\u2019aucun handicap s\u00e9v\u00e8re. Ils avaient alors entre 15 et 21 ans.<\/p>\n<p>\u00abDans l\u2019ensemble, souligne la jeune femme m\u00e9decin, les anciens pr\u00e9matur\u00e9s sont en bonne sant\u00e9.\u00bb Certes, elle a constat\u00e9 que \u00ab60% de ces adolescents ont des troubles visuels mineurs et 27% des troubles de la motricit\u00e9 fine ou grossi\u00e8re\u00bb. Mais ils n\u2019ont pas de difficult\u00e9s majeures \u00e0 l\u2019\u00e9cole.<\/p>\n<p><strong>A 16 ans, il n\u2019y a pas de diff\u00e9rence avec les autres \u00e9l\u00e8ves<\/strong><\/p>\n<p>Si, \u00e0 dix ans, ils ont plus de retard scolaire que la moyenne vaudoise, \u00ab\u00e0 16 ans, cette diff\u00e9rence a disparu; par contre, ils sont moins nombreux \u00e0 poursuivre des \u00e9tudes sup\u00e9rieures entre 16 et 19 ans (24% contre 35% dans la population g\u00e9n\u00e9rale)\u00bb.<\/p>\n<p>Barbara Monget note aussi que dans leur grande majorit\u00e9 (93%), ces jeunes \u00abont une bonne estime d\u2019eux-m\u00eames. Compar\u00e9s au groupe t\u00e9moin, ils ont moins d\u2019id\u00e9es suicidaires, de comportements d\u00e9viants ou \u00e0 risque et consomment moins d\u2019alcool et de haschich.\u00bb Et le m\u00e9decin de conclure: \u00abMalgr\u00e9 des probl\u00e8mes somatiques et neurologiques plus fr\u00e9quents, les anciens pr\u00e9matur\u00e9s ont une insertion socioprofessionnelle satisfaisante et estiment avoir une bonne qualit\u00e9 de vie.\u00bb<\/p>\n<h2>4 &#8211; C\u2019est parce que les m\u00e8res sont plus vieilles que leurs enfants naissent trop t\u00f4t<\/h2>\n<p>Il est vrai que l\u2019\u00e2ge moyen des m\u00e8res a augment\u00e9 en Suisse ces dix derni\u00e8res ann\u00e9es, passant d\u2019environ 28 \u00e0 31 ans. Cela \u00abentra\u00eene une augmentation des complications de la grossesse ainsi que le risque d\u2019accoucher pr\u00e9matur\u00e9ment\u00bb, constatent Yvan Vial et Jean-Fran\u00e7ois Tolsa. Mais ce n\u2019est l\u00e0 qu\u2019un des nombreux facteurs qui favorisent les naissances avant terme.<\/p>\n<p>Parmi les diverses causes de la pr\u00e9maturit\u00e9, le n\u00e9onatologue cite d\u2019abord \u00ables infections, bact\u00e9riennes ou virales, principalement des voies g\u00e9nitales basses\u00bb. Mais il arrive aussi qu\u2019une infection r\u00e9nale, urinaire ou m\u00eame une sinusite ou un \u00e9tat grippal conduisent \u00e0 une inflammation pouvant engendrer des contractions de l\u2019ut\u00e9rus.<\/p>\n<p>A cela il faut ajouter les grossesses multiples: qu\u2019elles soient naturelles ou qu\u2019elles r\u00e9sultent d\u2019un traitement de procr\u00e9ation m\u00e9dicalement assist\u00e9, elles sont responsables d\u2019environ un quart des naissances pr\u00e9matur\u00e9es. Il faut aussi inclure certaines malformations ou syndromes du f\u0153tus qui emp\u00eachent ce dernier de bien se d\u00e9velopper: dans ces circonstances, les m\u00e9decins peuvent \u00eatre conduits \u00e0 provoquer, volontairement, l\u2019accouchement avant terme.<\/p>\n<p>Ils peuvent aussi \u00eatre amen\u00e9s \u00e0 prendre cette d\u00e9cision dans d\u2019autres situations. Notamment lorsque la m\u00e8re a un ut\u00e9rus mal form\u00e9 et qui \u00abn\u2019est pas assez souple pour se distendre normalement\u00bb, comme le pr\u00e9cise Yvan Vial. Sans compter, ajoute l\u2019obst\u00e9tricien, que certaines naissances pr\u00e9matur\u00e9es sont dues au \u00abstress\u00bb de la m\u00e8re, ou \u00e0 des \u00abconditions socio-\u00e9conomiques\u00bb: il est bien connu qu\u2019une femme qui est oblig\u00e9e de porter r\u00e9guli\u00e8rement de lourdes charges risque d\u2019accoucher avant terme.<\/p>\n<h2>5 &#8211; La Suisse est l\u2019une des championnes des pr\u00e9matur\u00e9s en Europe<\/h2>\n<p>C\u2019est en effet ce qui ressort d\u2019une \u00e9tude publi\u00e9e, en juillet dernier, par l\u2019Office f\u00e9d\u00e9ral de la statistique. Selon cette enqu\u00eate, la Suisse, avec 9% d\u2019enfants n\u00e9s avant terme, arriverait en deuxi\u00e8me position apr\u00e8s l\u2019Autriche.<\/p>\n<p>Cette enqu\u00eate provoque toutefois un certain scepticisme de la part de Jean-Fran\u00e7ois Tolsa. Ce dernier remarque en effet que les conclusions de l\u2019Office reposent sur une \u00e9tude r\u00e9trospective incluant seulement 63 000 des quelque 72 000 naissances annonc\u00e9es en 2004. \u00abEnviron 13% des donn\u00e9es n\u2019\u00e9taient pas suffisamment fiables pour entrer dans cette \u00e9tude\u00bb, ce qui en fausse partiellement les r\u00e9sultats.<\/p>\n<p><strong>Des donn\u00e9es incompl\u00e8tes<\/strong><\/p>\n<p>Surtout, le n\u00e9onatologue du CHUV s\u2019interroge sur les donn\u00e9es de base utilis\u00e9es pour mener cette enqu\u00eate: \u00abL\u2019enregistrement syst\u00e9matique de l\u2019\u00e2ge de gestation pour toutes les naissances intervenant en Suisse n\u2019a commenc\u00e9 qu\u2019au 1er janvier 2007.\u00bb On peut donc s\u00e9rieusement douter de la pertinence de ces statistiques et sur le r\u00e9sultat de comparaisons avec des pays qui, eux non plus, \u00abn\u2019enregistrent pas les dur\u00e9es de gestation\u00bb.<\/p>\n<p>\u00abCe n\u2019est donc qu\u2019\u00e0 partir de 2008 que nous disposerons d\u2019une statistique pr\u00e9cise sur le nombre de pr\u00e9matur\u00e9s dans notre pays et que nous pourrons faire des comparaisons dans la dur\u00e9e. Attendons, avant de distribuer des m\u00e9dailles!\u00bb conclut le m\u00e9decin.<\/p>\n<p><strong>Entre 7 et 10% de pr\u00e9matur\u00e9s<\/strong><\/p>\n<p>En patientant, on en est r\u00e9duit aux estimations selon lesquelles le taux de pr\u00e9matur\u00e9s se situerait entre 7% et 10% en Europe occidentale. Au CHUV, cette proportion \u2013 qui est d\u2019ailleurs rest\u00e9e quasiment constante au cours des dix derni\u00e8res ann\u00e9es \u2013 oscille entre 13% et 15%. N\u2019allez pas croire que l\u2019h\u00f4pital vaudois est un champion en la mati\u00e8re. Ce taux \u00e9lev\u00e9 de pr\u00e9matur\u00e9s s\u2019explique simplement par le fait que ses services d\u2019obst\u00e9trique et de n\u00e9onatologie font du CHUV un Centre p\u00e9rinatal de r\u00e9f\u00e9rence. C\u2019est donc vers lui que sont achemin\u00e9es toutes les femmes de Suisse romande qui \u00e0 la maternit\u00e9 du CHUV ont des grossesses \u00e0 risque, \u00e0 l\u2019exception de celles habitant dans le canton de Gen\u00e8ve.<\/p>\n<h2>6 &#8211; Les m\u00e9decins ont tendance \u00e0 faire de l\u2019acharnement th\u00e9rapeutique<\/h2>\n<p>Jean-Fran\u00e7ois Tolsa tient \u00e0 mettre les choses au point: \u00abCertaines familles craignent que l\u2019on soit jusqu\u2019au-boutiste. Ce n\u2019est pas le cas, nous ne faisons pas d\u2019acharnement th\u00e9rapeutique.\u00bb Les m\u00e9decins suisses peuvent en effet s\u2019appuyer sur les recommandations \u00e9thiques de l\u2019Acad\u00e9mie Suisse des Sciences M\u00e9dicales et de la Soci\u00e9t\u00e9 Suisse de N\u00e9onatologie. Celles-ci pr\u00e9cisent que \u00absur la base des donn\u00e9es actuellement disponibles sur la mortalit\u00e9 et la morbidit\u00e9 \u00e0 long terme, la prise en charge des pr\u00e9matur\u00e9s d\u2019un \u00e2ge de gestation inf\u00e9rieur \u00e0 24 semaines devra en r\u00e8gle g\u00e9n\u00e9rale se limiter \u00e0 des mesures palliatives\u00bb. Au-del\u00e0 de 24 semaines, \u00abla d\u00e9cision quant \u00e0 la pertinence d\u2019une prise en charge intensive incombe \u00e0 une \u00e9quipe de n\u00e9onatologie exp\u00e9riment\u00e9e\u00bb.<\/p>\n<p>Ces r\u00e8gles \u00e9thiques sont \u00abune des qualit\u00e9s de notre syst\u00e8me\u00bb, souligne le m\u00e9decin vaudois qui constate que dans d\u2019autres pays, notamment aux Etats-Unis, le personnel m\u00e9dical soignant et les parents n\u2019ont pas le choix.<\/p>\n<p><strong>Estimer les chances<\/strong><\/p>\n<p>Au CHUV comme dans les autres h\u00f4pitaux suisses, il revient donc aux soignants d\u2019estimer \u00abraisonnablement\u00bb les chances et les risques de l\u2019enfant. \u00abLes discussions se font toujours dans le cadre d\u2019\u00e9quipes pluridisciplinaires, souligne Yvan Vial. Aucun d\u2019entre nous ne prend de d\u00e9cision dans son coin.\u00bb Ensuite, \u00abnous informons les parents des risques qu\u2019encourt leur enfant et nous tenons compte de leur avis\u00bb, poursuit Jean-Fran\u00e7ois Tolsa. Mais, afin d\u2019\u00e9viter aux parents le trop gros poids psychologique que repr\u00e9sente une telle d\u00e9cision, c\u2019est en g\u00e9n\u00e9ral \u00abnous qui la prenons\u00bb.<\/p>\n<p>Il arrive toutefois qu\u2019un p\u00e8re et une m\u00e8re refusent l\u2019avis de l\u2019\u00e9quipe m\u00e9dicale, et lui demandent de continuer \u00e0 traiter leur b\u00e9b\u00e9. Corine Stadelmann-Diaw, infirmi\u00e8re clinicienne qui travaille depuis vingt ans au service de n\u00e9onatologie du CHUV, se souvient de situations o\u00f9 \u00ables parents s\u2019\u00e9taient fortement oppos\u00e9s \u00e0 l\u2019arr\u00eat des soins. Mais au bout de quelques semaines, voyant que leur enfant n\u2019allait pas mieux, ils ont demand\u00e9 de pouvoir rediscuter avec l\u2019\u00e9quipe m\u00e9dicale. Ils avaient simplement besoin d\u2019un peu plus de temps.\u00bb<\/p>\n<p><strong>\u00abL\u2019aspect difficile de notre m\u00e9tier\u00bb<\/strong><\/p>\n<p>Reste que, selon Jean-Fran\u00e7ois Tolsa, prendre la d\u00e9cision de cesser de traiter un pr\u00e9matur\u00e9 \u00abrepr\u00e9sente l\u2019aspect difficile de notre m\u00e9tier. Il ne faut pas que cela arrive trop souvent.\u00bb Corinne Stadelmann-Diaw souligne aussi qu\u2019il est \u00abdifficile d\u2019\u00eatre plac\u00e9 face au d\u00e9c\u00e8s d\u2019un individu qui est au d\u00e9but de sa vie\u00bb. Mais, en contrepartie, l\u2019infirmi\u00e8re \u00e9prouve aussi \u00abde grandes satisfactions\u00bb dans son travail, car, dit-elle, \u00abnous avons de nombreux retours des parents qui viennent nous voir pour nous montrer ce que sont devenus leurs enfants\u00bb.<\/p>\n<p>Car si les pr\u00e9matur\u00e9s, dans les premiers jours ou semaines de leur vie, n\u00e9cessitent un suivi m\u00e9dical, et m\u00eame parfois des soins intensifs, dans leur majorit\u00e9, ils deviennent ensuite des enfants comme les autres.<\/p>\n<p style=\"text-align: right\">Elisabeth Gordon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la fin des ann\u00e9es 1980, les p\u00e9diatres ne pouvaient rien faire pour un enfant n\u00e9 avant 28 semaines de grossesse. Aujourd\u2019hui, la fronti\u00e8re entre la vie et la mort &hellip; <\/p>\n","protected":false},"author":158,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[30,8732],"tags":[44],"class_list":{"0":"post-1135","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-no-40","7":"category-sante","8":"tag-elisabeth-gordon"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/users\/158"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":0,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/allezsavoir\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}