{"id":2141,"date":"2015-06-23T10:00:32","date_gmt":"2015-06-23T08:00:32","guid":{"rendered":"http:\/\/wp.unil.ch\/acidul\/?p=2141"},"modified":"2024-07-12T17:30:18","modified_gmt":"2024-07-12T15:30:18","slug":"etats-generaux-de-la-recherche-revendications-et-petition","status":"publish","type":"post","link":"https:\/\/wp.unil.ch\/acidul\/2015\/06\/23\/etats-generaux-de-la-recherche-revendications-et-petition\/","title":{"rendered":"\u00c9tats g\u00e9n\u00e9raux de la recherche : revendications et p\u00e9tition"},"content":{"rendered":"<p>Le 24 avril dernier ont eu lieu les seconds \u00c9tats g\u00e9n\u00e9raux de la recherche en Suisse. Cette \u00e9dition a rencontr\u00e9 le m\u00eame succ\u00e8s que la premi\u00e8re \u00e9dition en 2012. Apr\u00e8s une matin\u00e9e de conf\u00e9rences, l&rsquo;apr\u00e8s-midi a \u00e9t\u00e9 consacr\u00e9e \u00e0 la discussion, et a abouti \u00e0 des revendications concr\u00e8tes \u00e0 mettre en \u0153uvre dans les Hautes \u00c9coles suisses.<\/p>\n<p>Le document qui regroupe les revendications est en cours de finalisation. Il sera \u00e9galement traduit en plusieurs langues et diffus\u00e9 largement.<\/p>\n<p>Il a \u00e9galement \u00e9t\u00e9 d\u00e9cid\u00e9 qu&rsquo;ACIDUL lancera une p\u00e9tition cet automne autour des revendications qui sont sorties de ces seconds \u00c9tats g\u00e9n\u00e9raux. Nous vous tiendrons \u00e9videmment au courant d\u00e8s que l\u2019action commencera.<\/p>\n<p>N&rsquo;h\u00e9sitez pas \u00e0 nous contacter si vous voulez recevoir des informations plus fr\u00e9quentes sur la suite de cette action. Un simple mail \u00e0\u00a0<a href=\"mailto:acidul@unil.ch\">acidul@unil.ch<\/a>\u00a0suffit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 24 avril dernier ont eu lieu les seconds \u00c9tats g\u00e9n\u00e9raux de la recherche en Suisse. Cette \u00e9dition a rencontr\u00e9 le m\u00eame succ\u00e8s que la premi\u00e8re \u00e9dition en 2012. Apr\u00e8s une matin\u00e9e de conf\u00e9rences, l&rsquo;apr\u00e8s-midi a \u00e9t\u00e9 consacr\u00e9e \u00e0 la discussion, et a abouti \u00e0 des revendications concr\u00e8tes \u00e0 mettre en \u0153uvre dans les Hautes [&hellip;]<\/p>\n","protected":false},"author":197,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[61888,66741,9905],"tags":[],"class_list":{"0":"post-2141","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-conditions-de-travail","7":"category-petitions","8":"category-recherche"},"_links":{"self":[{"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/posts\/2141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/comments?post=2141"}],"version-history":[{"count":2,"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/posts\/2141\/revisions"}],"predecessor-version":[{"id":3998,"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/posts\/2141\/revisions\/3998"}],"wp:attachment":[{"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/media?parent=2141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/categories?post=2141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.unil.ch\/acidul\/wp-json\/wp\/v2\/tags?post=2141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}